{"id":6181,"count":1,"description":"","link":"https:\/\/crentassos.com.br\/blog\/tag\/pokemon-go","name":"pok\u00e9mon go","slug":"pokemon-go","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>pok\u00e9mon go Archives - Crentassos Produ\u00e7\u00f5es Subversivas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crentassos.com.br\/blog\/tag\/pokemon-go\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"pok\u00e9mon go Archives - Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crentassos.com.br\/blog\/tag\/pokemon-go\" \/>\n<meta property=\"og:site_name\" content=\"Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@crentassos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/tag\\\/pokemon-go\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/tag\\\/pokemon-go\",\"name\":\"pok\u00e9mon go Archives - Crentassos Produ\u00e7\u00f5es Subversivas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/tag\\\/pokemon-go#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/tag\\\/pokemon-go#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"pok\u00e9mon go\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"description\":\"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"width\":300,\"height\":300,\"caption\":\"Crentassos Produ\u00e7\u00f5es Subversivas\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/crentassos\",\"https:\\\/\\\/x.com\\\/crentassos\",\"https:\\\/\\\/www.instagram.com\\\/crentassos\",\"https:\\\/\\\/www.youtube.com\\\/crentassos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"pok\u00e9mon go Archives - Crentassos Produ\u00e7\u00f5es Subversivas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crentassos.com.br\/blog\/tag\/pokemon-go","og_locale":"pt_BR","og_type":"article","og_title":"pok\u00e9mon go Archives - Crentassos Produ\u00e7\u00f5es Subversivas","og_url":"https:\/\/crentassos.com.br\/blog\/tag\/pokemon-go","og_site_name":"Crentassos Produ\u00e7\u00f5es Subversivas","twitter_card":"summary_large_image","twitter_site":"@crentassos","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/crentassos.com.br\/blog\/tag\/pokemon-go","url":"https:\/\/crentassos.com.br\/blog\/tag\/pokemon-go","name":"pok\u00e9mon go Archives - Crentassos Produ\u00e7\u00f5es Subversivas","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/crentassos.com.br\/blog\/tag\/pokemon-go#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/crentassos.com.br\/blog\/tag\/pokemon-go#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/crentassos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"pok\u00e9mon go"}]},{"@type":"WebSite","@id":"https:\/\/crentassos.com.br\/blog\/#website","url":"https:\/\/crentassos.com.br\/blog\/","name":"Crentassos Produ\u00e7\u00f5es Subversivas","description":"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos","publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crentassos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/crentassos.com.br\/blog\/#organization","name":"Crentassos Produ\u00e7\u00f5es Subversivas","url":"https:\/\/crentassos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","width":300,"height":300,"caption":"Crentassos Produ\u00e7\u00f5es Subversivas"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/crentassos","https:\/\/x.com\/crentassos","https:\/\/www.instagram.com\/crentassos","https:\/\/www.youtube.com\/crentassos"]}]}},"_links":{"self":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/tags\/6181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=6181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}