{"id":9153,"date":"2013-05-15T15:17:27","date_gmt":"2013-05-15T18:17:27","guid":{"rendered":"http:\/\/crentassos.com.br\/blog\/?p=9153"},"modified":"2013-05-15T15:17:27","modified_gmt":"2013-05-15T18:17:27","slug":"uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr","status":"publish","type":"post","link":"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html","title":{"rendered":"Uma nova Lei \u00c1urea | Ed Ren\u00e9 Kivitz entrevista Dep. Carlos Bezerra Jr."},"content":{"rendered":"<p>Quando dizemos &#8220;BANCADA EVANGELICA&#8221; ao tratarmos de assuntos da politica, de maneira geral e muito compreensivel, ficamos com o estomago mechido, e sentimos vontade de devolver nossa ultima refei\u00e7\u00e3o&#8230;\u00a0 Contudo, ainda h\u00e1, dentre os seguidores de Cristo que se envolvem nessa area, gente que ainda est\u00e1 tentando agir de maneira CRIST\u00c3 dentre todo aquele lixo&#8230;<\/p>\n\n<p>Enquanto ainda tem gente preocupada com a o casamento gay, com a ditadura comunista e com tantas outras fabulas, ainda tem gente querendo preservar o mais preciso dentro do cristianismo&#8230; N\u00e3o \u00e9 a moralidade, nem a religi\u00e3o institucionalizada&#8230; Mas VIDAS HUMANAS!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando dizemos &#8220;BANCADA EVANGELICA&#8221; ao tratarmos de assuntos da politica, de maneira geral e muito compreensivel, ficamos com o estomago mechido, e [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":9154,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[122],"tags":[2270,1392,481,6],"class_list":["post-9153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videos","tag-carlos-bezerra-jr","tag-ed-rene-kivtz","tag-entrevista","tag-video","post-with-thumbnail","post-with-thumbnail-large"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uma nova Lei \u00c1urea | Ed Ren\u00e9 Kivitz entrevista Dep. Carlos Bezerra Jr.  - Crentassos Produ\u00e7\u00f5es Subversivas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uma nova Lei \u00c1urea | Ed Ren\u00e9 Kivitz entrevista Dep. Carlos Bezerra Jr.  - Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"og:description\" content=\"Quando dizemos &#8220;BANCADA EVANGELICA&#8221; ao tratarmos de assuntos da politica, de maneira geral e muito compreensivel, ficamos com o estomago mechido, e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html\" \/>\n<meta property=\"og:site_name\" content=\"Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/crentassos\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-15T18:17:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/490.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"425\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristiano Machado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@crentassos\" \/>\n<meta name=\"twitter:site\" content=\"@crentassos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristiano Machado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/05\\\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/05\\\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html\"},\"author\":{\"name\":\"Cristiano Machado\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/7ec3329a98c44e20ccd6cc2c9e18acbd\"},\"headline\":\"Uma nova Lei \u00c1urea | Ed Ren\u00e9 Kivitz entrevista Dep. Carlos Bezerra Jr.\",\"datePublished\":\"2013-05-15T18:17:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/05\\\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html\"},\"wordCount\":116,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/05\\\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/490.jpg\",\"keywords\":[\"Carlos Bezerra Jr\",\"ed rene kivtz\",\"entrevista\",\"video\"],\"articleSection\":[\"V\u00eddeos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/05\\\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/05\\\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/05\\\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html\",\"name\":\"Uma nova Lei \u00c1urea | Ed Ren\u00e9 Kivitz entrevista Dep. Carlos Bezerra Jr. - Crentassos Produ\u00e7\u00f5es Subversivas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/05\\\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/05\\\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/490.jpg\",\"datePublished\":\"2013-05-15T18:17:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/05\\\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/05\\\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/05\\\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#primaryimage\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/490.jpg\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/490.jpg\",\"width\":425,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/05\\\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uma nova Lei \u00c1urea | Ed Ren\u00e9 Kivitz entrevista Dep. Carlos Bezerra Jr.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"description\":\"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"width\":300,\"height\":300,\"caption\":\"Crentassos Produ\u00e7\u00f5es Subversivas\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/crentassos\",\"https:\\\/\\\/x.com\\\/crentassos\",\"https:\\\/\\\/www.instagram.com\\\/crentassos\",\"https:\\\/\\\/www.youtube.com\\\/crentassos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/7ec3329a98c44e20ccd6cc2c9e18acbd\",\"name\":\"Cristiano Machado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g\",\"caption\":\"Cristiano Machado\"},\"description\":\"Cristiano Machado \u00e9 o culpado pelo inicio do COLETIVO CRENTASSOS PRODU\u00c7\u00d5ES SUBVERSIVAS e atua como auxiliar de cirurgi\u00e3o barbeiro, tocando o bumbo, jogando malabares, preparando o elixir, costurando amputa\u00e7\u00f5es e demais atividades relacionadas \u00e0 sua ocupa\u00e7\u00e3o. Pensa n\u00e3o vida em forma de pergunta e nunca de resposta, e tem um profundo sentimento de gratid\u00e3o e amor por sua esposa e filha. Religi\u00e3o: Crist\u00e3o Protestante Reformando-se Estado Civil: Inteiramente apaixonado\",\"sameAs\":[\"http:\\\/\\\/crentassos.com.br\\\/blog\"],\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/author\\\/o_cristiano\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uma nova Lei \u00c1urea | Ed Ren\u00e9 Kivitz entrevista Dep. Carlos Bezerra Jr.  - Crentassos Produ\u00e7\u00f5es Subversivas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html","og_locale":"pt_BR","og_type":"article","og_title":"Uma nova Lei \u00c1urea | Ed Ren\u00e9 Kivitz entrevista Dep. Carlos Bezerra Jr.  - Crentassos Produ\u00e7\u00f5es Subversivas","og_description":"Quando dizemos &#8220;BANCADA EVANGELICA&#8221; ao tratarmos de assuntos da politica, de maneira geral e muito compreensivel, ficamos com o estomago mechido, e [&hellip;]","og_url":"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html","og_site_name":"Crentassos Produ\u00e7\u00f5es Subversivas","article_publisher":"http:\/\/www.facebook.com\/crentassos","article_published_time":"2013-05-15T18:17:27+00:00","og_image":[{"width":425,"height":640,"url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/490.jpg","type":"image\/jpeg"}],"author":"Cristiano Machado","twitter_card":"summary_large_image","twitter_creator":"@crentassos","twitter_site":"@crentassos","twitter_misc":{"Escrito por":"Cristiano Machado","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#article","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html"},"author":{"name":"Cristiano Machado","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/7ec3329a98c44e20ccd6cc2c9e18acbd"},"headline":"Uma nova Lei \u00c1urea | Ed Ren\u00e9 Kivitz entrevista Dep. Carlos Bezerra Jr.","datePublished":"2013-05-15T18:17:27+00:00","mainEntityOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html"},"wordCount":116,"commentCount":0,"publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/490.jpg","keywords":["Carlos Bezerra Jr","ed rene kivtz","entrevista","video"],"articleSection":["V\u00eddeos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html","url":"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html","name":"Uma nova Lei \u00c1urea | Ed Ren\u00e9 Kivitz entrevista Dep. Carlos Bezerra Jr. - Crentassos Produ\u00e7\u00f5es Subversivas","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#primaryimage"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/490.jpg","datePublished":"2013-05-15T18:17:27+00:00","breadcrumb":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#primaryimage","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/490.jpg","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/490.jpg","width":425,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/crentassos.com.br\/blog\/2013\/05\/uma-nova-lei-aurea-ed-rene-kivitz-entrevista-dep-carlos-bezerra-jr.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/crentassos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Uma nova Lei \u00c1urea | Ed Ren\u00e9 Kivitz entrevista Dep. Carlos Bezerra Jr."}]},{"@type":"WebSite","@id":"https:\/\/crentassos.com.br\/blog\/#website","url":"https:\/\/crentassos.com.br\/blog\/","name":"Crentassos Produ\u00e7\u00f5es Subversivas","description":"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos","publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crentassos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/crentassos.com.br\/blog\/#organization","name":"Crentassos Produ\u00e7\u00f5es Subversivas","url":"https:\/\/crentassos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","width":300,"height":300,"caption":"Crentassos Produ\u00e7\u00f5es Subversivas"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/crentassos","https:\/\/x.com\/crentassos","https:\/\/www.instagram.com\/crentassos","https:\/\/www.youtube.com\/crentassos"]},{"@type":"Person","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/7ec3329a98c44e20ccd6cc2c9e18acbd","name":"Cristiano Machado","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g","caption":"Cristiano Machado"},"description":"Cristiano Machado \u00e9 o culpado pelo inicio do COLETIVO CRENTASSOS PRODU\u00c7\u00d5ES SUBVERSIVAS e atua como auxiliar de cirurgi\u00e3o barbeiro, tocando o bumbo, jogando malabares, preparando o elixir, costurando amputa\u00e7\u00f5es e demais atividades relacionadas \u00e0 sua ocupa\u00e7\u00e3o. Pensa n\u00e3o vida em forma de pergunta e nunca de resposta, e tem um profundo sentimento de gratid\u00e3o e amor por sua esposa e filha. Religi\u00e3o: Crist\u00e3o Protestante Reformando-se Estado Civil: Inteiramente apaixonado","sameAs":["http:\/\/crentassos.com.br\/blog"],"url":"https:\/\/crentassos.com.br\/blog\/author\/o_cristiano"}]}},"_links":{"self":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/9153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=9153"}],"version-history":[{"count":1,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/9153\/revisions"}],"predecessor-version":[{"id":9155,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/9153\/revisions\/9155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media\/9154"}],"wp:attachment":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=9153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=9153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=9153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}