{"id":8912,"date":"2013-04-15T16:25:40","date_gmt":"2013-04-15T19:25:40","guid":{"rendered":"http:\/\/crentassos.com.br\/blog\/?p=8912"},"modified":"2013-04-16T16:27:11","modified_gmt":"2013-04-16T19:27:11","slug":"quem-vive-pela-lei-ponderacoes-sobre-a-pl122","status":"publish","type":"post","link":"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html","title":{"rendered":"Quem vive pela lei!? (pondera\u00e7\u00f5es sobre a PL122)"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Eu li recentemente a PL122, em vista de tudo que est\u00e1 acontecendo para tentar entender o porque de tanta briga.<\/p>\n<p style=\"text-align: justify;\">Bom antes de prosseguir, s\u00f3 quero colocar que a PL122 , assim como tantas outras leis (Maria de Penha, Lei seca&#8230;) \u00e9 um lei que \u00a0n\u00e3o vai resolver o problema.. a lei n\u00e3o tem esse poder. \u00a0Se tivesse, nunca mais haveria mulheres com hematomas na cara(presente dos maridos) ou pessoas morrendo alcoolizadas em carros acidentados. \u00c9 claro que alguns ir\u00e3o responder por ela, ser\u00e3o julgados e presos.. mas aqueles que fazem o mal para outra pessoa, n\u00e3o est\u00e3o debaixo de lei nenhuma.. n\u00e3o se baseiam na lei para fazer o que fazem.. ao contr\u00e1rio, seu prazer \u00e9 justamente transgredi-la, ou seja, isso n\u00e3o vai diminuir a viol\u00eancia.. \u00e9 perigoso at\u00e9 mesmo que ela aumente. Quem vai sofrer ser\u00e1 o cidad\u00e3o mediano que, por descuido ou opini\u00e3o pessoal, responder\u00e1 a lei..<\/p>\n<p style=\"text-align: justify;\">Isso posto, prossigo agora com minhas considera\u00e7\u00f5es sobre para a PL122.<\/p>\n<p style=\"text-align: justify;\">Primeiro: Ele \u00e9 herdeira (ou continua\u00e7\u00e3o) de outra lei que foi decretada em 1940 e desde ent\u00e3o vem recebendo emendas. Basicamente ela define os crimes resultantes de discrimina\u00e7\u00e3o ou preconceito de ra\u00e7a, cor, etnia, religi\u00e3o, proced\u00eancia nacional, g\u00eanero, sexo, orienta\u00e7\u00e3o sexual e identidade de g\u00eanero. A emenda PL122 apenas focaliza alguns direitos espec\u00edficos de um grupo dentro dos citados. No caso os homossexuais.<\/p>\n<p style=\"text-align: justify;\">Segundo. Ao ler a lei percebi uma coisa importante: se a minha opini\u00e3o sobre homossexualidade for de cunho religioso e n\u00e3o tem por inten\u00e7\u00e3o incitar viol\u00eancia contra quem pratica homossexualidade, ent\u00e3o n\u00e3o pode haver condena\u00e7\u00e3o, j\u00e1 que a pr\u00f3pria lei ampara o direito religioso. Trocando em mi\u00fados: Se eu disser que sou contra a homossexualidade porque creio, como crist\u00e3o, que Deus n\u00e3o a aprova, n\u00e3o posso ser condenado, perseguido ou calado, j\u00e1 que a mesma lei que ampara o homossexual , ampara tamb\u00e9m o religioso.<\/p>\n<p style=\"text-align: justify;\">Terceiro: Tem outra situa\u00e7\u00e3o mais complicada. Por exemplo: Vamos supor que eu contrate um Gay negro para trabalhar na minha empresa, sem saber de sua op\u00e7\u00e3o sexual. Por\u00e9m percebo que ao longo de um certo tempo, essa pessoa n\u00e3o \u00e9 competente para o cargo, ent\u00e3o a despe\u00e7o. Essa pessoa pode me processar alegando racismo ou homofobia segundo a nova lei? Aparentemente pode. Essa seria uma boa raz\u00e3o para uma discuss\u00e3o interessante sobre excessos na lei. Infelizmente n\u00e3o a temos.<\/p>\n<p style=\"text-align: justify;\">Porque n\u00e3o?! porque como crist\u00e3os estamos mais ocupados defendendo a institui\u00e7\u00e3o igreja e a institui\u00e7\u00e3o fam\u00edlia. Na minha opini\u00e3o, uma tremenda hipocrisia.<\/p>\n<p style=\"text-align: justify;\">Dizem alguns que n\u00e3o podemos permitir que gays tenha a liberdade de se beijar na frente da igreja ou de estarem num culto, sendo gay assumido. Sobre isso pergunto: N\u00e3o podemos tolerar os gays se beijando na frente da igreja mas toleramos coisas que s\u00e3o de fato injusti\u00e7as vertentes da desigualdade social como mendigos, moradores de rua, os que consomem crack e que dormem as portas da mesma, os que passam por n\u00f3s ou batem no vidro do nosso carro pedido migalhas e n\u00f3s os esnobamos. Isso pode? Quando fechamos os olhos para tanta corrup\u00e7\u00e3o, mentiras, abusos dentro da igreja, isso \u00e9 tranquilo?! Se for, beleza, crucifiquemos o beijo gay! Podemos tamb\u00e9m condenar um casal gay assumido participando de um culto, se entendermos que sexo entre pessoas do mesmo sexo \u00e9 pecado. Ent\u00e3o, se isso for errado (ou pecado que impe\u00e7a algu\u00e9m de freq\u00fcentar o culto a Deus), podemos condenar tamb\u00e9m ped\u00f3filos enrustidos da igreja!? (entendendo que ambos s\u00e3o pecados mas de forma alguma eq\u00fcivalendo ou comparando os tipos de pecado). E os casais que vivem um casamento ridiculamente falso?! Sexo a vontade n\u00e3o conjugal entre pastores, ministros de louvor e adolescentes? e que tal punir todo aquele que dentro da igreja \u00e9 viciado em pornografia?! Vamos expuls\u00e1-los todos sem piedade e amor! Vamos usar a mesma medida para todos?! Se for assim, beleza. Tenhamos mais piedade de quem n\u00e3o esconde seu pecado.<\/p>\n<p style=\"text-align: justify;\">Defender a fam\u00edlia \u00e9 de fato um gesto nobre. Creio que a fam\u00edlia \u00e9 fundamental para a sociedade. Por\u00e9m como crist\u00e3os, temos aumentado absurdamente o n\u00edvel de div\u00f3rcio em nosso meio. Pastores que sacrificam a fam\u00edlia em prol do \u201cminist\u00e9rio\u201d. Artista com a agenda cheia que n\u00e3o podem ver a fam\u00edlia mais que tr\u00eas ou quatro vezes por m\u00eas. Filhos que crescem sem pais e que odeiam o cristianismo ut\u00f3pico pregado em casa. Se queremos defender a fam\u00edlia, que comecemos com as nossas!! Afinal com que moral estamos querendo defender a fam\u00edlia tradicional se nem n\u00f3s mesmos conseguimos isso?!<\/p>\n<p style=\"text-align: justify;\">Os homossexuais\u00a0 querem se casar?! que se casem! eles far\u00e3o isso com ou sem lei. Que seja pela lei ent\u00e3o. Querem adotar? que adotem! \u00e9 melhor uma crian\u00e7a sob um teto sendo amada do que abandonada. Se voc\u00ea como crist\u00e3o acha ruim! Adote tamb\u00e9m! Fazendo isso voc\u00ea cumpre o mandamento.<\/p>\n<p style=\"text-align: justify;\">Olhando para PL122 n\u00e3o vejo que ela restrinja o crist\u00e3o de ser crist\u00e3o! Pode restringir o crist\u00e3o de ser religioso, prepotente, dono da verdade, hipocrita, seletivo ou simplesmente babaca. Mas poder\u00e1 continuar sendo crist\u00e3o. A lei n\u00e3o passa nem perto desse direito.\u00a0 Al\u00edas n\u00e3o tem nada dentro da PL122 ou outra lei que eu conhe\u00e7a, que me impe\u00e7a de ser crist\u00e3o e exercer culto a ele. Desde Roma \u00e9 assim. Temos a liberdade de sairmos a rua para falar de Jesus e damos (ou prescisamos dar) liberdade para quem quer sair \u00e0s ruas defender o que quiserem tamb\u00e9m.. isso chama-se democracia.<\/p>\n<p style=\"text-align: justify;\">Teremos que lidar com tens\u00f5es? claro! Ser crist\u00e3o \u00e9 lidar com tens\u00f5es! talvez seremos presos por isso?! \u00f3timo! quem sabe a gente n\u00e3o aviva nosso cora\u00e7\u00e3o quanto ao \u201cser seguidores de Cristo\u201d. Seremos impedidos de falar do amor de Jesus?! nunca! somente n\u00f3s mesmo podemos fazer isso&#8230; e fazemos.. quando brigamos uma briga pol\u00edtica por direitos quando, em tese, renunciamos nossos direito por Cristo.<\/p>\n<p style=\"text-align: justify;\">Enfim, de toda a discuss\u00e3o at\u00e9 agora, quase nada ouvi sobre a lei PL122. \u00c9 uma pena. Deveria ser debatida, analisada, ponderada, e depois aprovada, se visasse o bem estar coletivo. Somos fantoches na m\u00e3o de algu\u00e9m&#8230; e gostamos disso.. pois \u00e9 melhor do que ter que pensar&#8230;. al\u00e9m do mais preferimos discutir sobre quem tem mais poder do que sobre quem ama mais ao inv\u00e9s de amar aquele que consideramos nosso inimigo..<\/p>\n<p style=\"text-align: justify;\">At\u00e9 mesmo nossos representantes evang\u00e9licos, quando na m\u00eddia, apenas d\u00e3o show de religiosidade, ou pior, posam de estelionat\u00e1rios. Mas isso n\u00e3o importa n\u00e3o \u00e9!? Precisamos sair na ruas marchando em nome de Jesus em mais uma jogada pol\u00edtica para eleger fulano ou ciclano.\u00a0 No fim o que queremos \u00e9 o Brasil para Cristo, os lucros para n\u00f3s, os corpos para os abutres e as almas que se explodam.<\/p>\n<p style=\"text-align: justify;\">Resumindo: N\u00e3o sou gay nem homof\u00f3bico. N\u00e3o sou a favor da lei quando ela oprime o direito de igualdade. N\u00e3o sou a favor da injusti\u00e7a e viol\u00eancia assim como n\u00e3o sou a favor da justi\u00e7a cega e a paz sem voz. Sou a favor da vida. Como crist\u00e3o estou do lado dos oprimidos e \u00a0injusti\u00e7ados, sejam eles gays, crentes, ateus e quem quer que seja o que. Minha sugest\u00e3o \u00e9: leia sobre a lei e a lei. Defenda o que \u00e9 certo e n\u00e3o argumentos que soam certos. Seja gay ou n\u00e3o, seja inteligente, justo e procure o bem estar do pr\u00f3ximo. Conhe\u00e7a a verdade e seja liberto por ela&#8230;<\/p>\n<p style=\"text-align: justify;\">Termino lembrando das palavras de Jesus na cruz orando por aqueles que o puseram l\u00e1&#8230;.\u201dPerdoe-os Pai, eles n\u00e3o sabem o que fazem\u201d&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eu li recentemente a PL122, em vista de tudo que est\u00e1 acontecendo para tentar entender o porque de tanta briga. Bom antes [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":8941,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[112],"tags":[370,400,1549,630,2230,2169],"class_list":["post-8912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","tag-crentassos","tag-danni-distler","tag-gays","tag-homofobia","tag-p","tag-pl122","post-with-thumbnail","post-with-thumbnail-large"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quem vive pela lei!? (pondera\u00e7\u00f5es sobre a PL122) - Crentassos Produ\u00e7\u00f5es Subversivas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quem vive pela lei!? (pondera\u00e7\u00f5es sobre a PL122) - Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"og:description\" content=\"Eu li recentemente a PL122, em vista de tudo que est\u00e1 acontecendo para tentar entender o porque de tanta briga. Bom antes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html\" \/>\n<meta property=\"og:site_name\" content=\"Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/crentassos\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-15T19:25:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-04-16T19:27:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/BLOG-TEXTO-CENSURADO-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"573\" \/>\n\t<meta property=\"og:image:height\" content=\"443\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danni Distler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@crentassos\" \/>\n<meta name=\"twitter:site\" content=\"@crentassos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danni Distler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/04\\\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/04\\\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html\"},\"author\":{\"name\":\"Danni Distler\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f28a0d59813bb7ad4666178ea4c2cfd5\"},\"headline\":\"Quem vive pela lei!? (pondera\u00e7\u00f5es sobre a PL122)\",\"datePublished\":\"2013-04-15T19:25:40+00:00\",\"dateModified\":\"2013-04-16T19:27:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/04\\\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html\"},\"wordCount\":1357,\"commentCount\":33,\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/04\\\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/BLOG-TEXTO-CENSURADO-3.jpg\",\"keywords\":[\"crentassos\",\"danni distler\",\"gays\",\"homofobia\",\"P\",\"pl122\"],\"articleSection\":[\"Artigos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/04\\\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/04\\\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/04\\\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html\",\"name\":\"Quem vive pela lei!? (pondera\u00e7\u00f5es sobre a PL122) - Crentassos Produ\u00e7\u00f5es Subversivas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/04\\\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/04\\\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/BLOG-TEXTO-CENSURADO-3.jpg\",\"datePublished\":\"2013-04-15T19:25:40+00:00\",\"dateModified\":\"2013-04-16T19:27:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/04\\\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/04\\\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/04\\\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#primaryimage\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/BLOG-TEXTO-CENSURADO-3.jpg\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/BLOG-TEXTO-CENSURADO-3.jpg\",\"width\":573,\"height\":443},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/04\\\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quem vive pela lei!? (pondera\u00e7\u00f5es sobre a PL122)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"description\":\"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"width\":300,\"height\":300,\"caption\":\"Crentassos Produ\u00e7\u00f5es Subversivas\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/crentassos\",\"https:\\\/\\\/x.com\\\/crentassos\",\"https:\\\/\\\/www.instagram.com\\\/crentassos\",\"https:\\\/\\\/www.youtube.com\\\/crentassos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f28a0d59813bb7ad4666178ea4c2cfd5\",\"name\":\"Danni Distler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19f0efa0a4bbbe6d2b81b25c8aa112ade91c55ac3834001f3c0ac73e280de0cf?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19f0efa0a4bbbe6d2b81b25c8aa112ade91c55ac3834001f3c0ac73e280de0cf?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19f0efa0a4bbbe6d2b81b25c8aa112ade91c55ac3834001f3c0ac73e280de0cf?s=96&d=retro&r=g\",\"caption\":\"Danni Distler\"},\"description\":\"M\u00fasico, cantor, compositor, produtor musical, mission\u00e1rio contemporr\u00e2neo. Atua no meio musical h\u00e1 mais de 10 anos, viajando pelo Brasil e fora dele, atendendo a igrejas, eventos e fazendo shows em casa noturnas e bares.\",\"sameAs\":[\"http:\\\/\\\/www.dannidistler.com\"],\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/author\\\/dannidistler\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quem vive pela lei!? (pondera\u00e7\u00f5es sobre a PL122) - Crentassos Produ\u00e7\u00f5es Subversivas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html","og_locale":"pt_BR","og_type":"article","og_title":"Quem vive pela lei!? (pondera\u00e7\u00f5es sobre a PL122) - Crentassos Produ\u00e7\u00f5es Subversivas","og_description":"Eu li recentemente a PL122, em vista de tudo que est\u00e1 acontecendo para tentar entender o porque de tanta briga. Bom antes [&hellip;]","og_url":"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html","og_site_name":"Crentassos Produ\u00e7\u00f5es Subversivas","article_publisher":"http:\/\/www.facebook.com\/crentassos","article_published_time":"2013-04-15T19:25:40+00:00","article_modified_time":"2013-04-16T19:27:11+00:00","og_image":[{"width":573,"height":443,"url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/BLOG-TEXTO-CENSURADO-3.jpg","type":"image\/jpeg"}],"author":"Danni Distler","twitter_card":"summary_large_image","twitter_creator":"@crentassos","twitter_site":"@crentassos","twitter_misc":{"Escrito por":"Danni Distler","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#article","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html"},"author":{"name":"Danni Distler","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/f28a0d59813bb7ad4666178ea4c2cfd5"},"headline":"Quem vive pela lei!? (pondera\u00e7\u00f5es sobre a PL122)","datePublished":"2013-04-15T19:25:40+00:00","dateModified":"2013-04-16T19:27:11+00:00","mainEntityOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html"},"wordCount":1357,"commentCount":33,"publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/BLOG-TEXTO-CENSURADO-3.jpg","keywords":["crentassos","danni distler","gays","homofobia","P","pl122"],"articleSection":["Artigos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html","url":"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html","name":"Quem vive pela lei!? (pondera\u00e7\u00f5es sobre a PL122) - Crentassos Produ\u00e7\u00f5es Subversivas","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#primaryimage"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/BLOG-TEXTO-CENSURADO-3.jpg","datePublished":"2013-04-15T19:25:40+00:00","dateModified":"2013-04-16T19:27:11+00:00","breadcrumb":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#primaryimage","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/BLOG-TEXTO-CENSURADO-3.jpg","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/BLOG-TEXTO-CENSURADO-3.jpg","width":573,"height":443},{"@type":"BreadcrumbList","@id":"https:\/\/crentassos.com.br\/blog\/2013\/04\/quem-vive-pela-lei-ponderacoes-sobre-a-pl122.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/crentassos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Quem vive pela lei!? (pondera\u00e7\u00f5es sobre a PL122)"}]},{"@type":"WebSite","@id":"https:\/\/crentassos.com.br\/blog\/#website","url":"https:\/\/crentassos.com.br\/blog\/","name":"Crentassos Produ\u00e7\u00f5es Subversivas","description":"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos","publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crentassos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/crentassos.com.br\/blog\/#organization","name":"Crentassos Produ\u00e7\u00f5es Subversivas","url":"https:\/\/crentassos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","width":300,"height":300,"caption":"Crentassos Produ\u00e7\u00f5es Subversivas"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/crentassos","https:\/\/x.com\/crentassos","https:\/\/www.instagram.com\/crentassos","https:\/\/www.youtube.com\/crentassos"]},{"@type":"Person","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/f28a0d59813bb7ad4666178ea4c2cfd5","name":"Danni Distler","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/19f0efa0a4bbbe6d2b81b25c8aa112ade91c55ac3834001f3c0ac73e280de0cf?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19f0efa0a4bbbe6d2b81b25c8aa112ade91c55ac3834001f3c0ac73e280de0cf?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19f0efa0a4bbbe6d2b81b25c8aa112ade91c55ac3834001f3c0ac73e280de0cf?s=96&d=retro&r=g","caption":"Danni Distler"},"description":"M\u00fasico, cantor, compositor, produtor musical, mission\u00e1rio contemporr\u00e2neo. Atua no meio musical h\u00e1 mais de 10 anos, viajando pelo Brasil e fora dele, atendendo a igrejas, eventos e fazendo shows em casa noturnas e bares.","sameAs":["http:\/\/www.dannidistler.com"],"url":"https:\/\/crentassos.com.br\/blog\/author\/dannidistler"}]}},"_links":{"self":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/8912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=8912"}],"version-history":[{"count":4,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/8912\/revisions"}],"predecessor-version":[{"id":8948,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/8912\/revisions\/8948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media\/8941"}],"wp:attachment":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=8912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=8912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=8912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}