{"id":8678,"date":"2013-03-04T09:13:48","date_gmt":"2013-03-04T12:13:48","guid":{"rendered":"http:\/\/crentassos.com.br\/blog\/?p=8678"},"modified":"2013-03-04T09:13:48","modified_gmt":"2013-03-04T12:13:48","slug":"nascimento","status":"publish","type":"post","link":"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html","title":{"rendered":"Nascimento&#8230;"},"content":{"rendered":"<p>H<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8679 alignleft\" alt=\"Nascimentoo\" src=\"http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/nascimento-novo-negocio.jpg\" width=\"614\" height=\"461\" srcset=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/nascimento-novo-negocio.jpg 1024w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/nascimento-novo-negocio-300x225.jpg 300w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/nascimento-novo-negocio-620x465.jpg 620w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/nascimento-novo-negocio-160x120.jpg 160w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/>j n\u00e3o vim pra falar sobre teologia, miss\u00e3o, denunciar abusos nem nada do genero<\/p>\n<p>\u00c9 com muita alegria que a equipe do blog avisa que no dia 4 de mar\u00e7o de 2013, NASCEU O FILHO DO DANNI E DA LELLA \ud83d\ude42<\/p>\n<p>Sim, o bebezinho nasceu na noite de ontem e eu fui avisado pelo voxer, por uma voz rouca e sensivelmente emocionada, de que agora tem a familia Distler tem mais um membro&#8230;<\/p>\n<p>Parabens aos pais Danni e Lella e seja bem vindo, Emanuel \ud83d\ude42<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hj n\u00e3o vim pra falar sobre teologia, miss\u00e3o, denunciar abusos nem nada do genero \u00c9 com muita alegria que a equipe do [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":8679,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1412],"tags":[1405,400,1421],"class_list":{"0":"post-8678","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-jaba-sessoes","8":"tag-alegria","9":"tag-danni-distler","10":"tag-nascimento","12":"post-with-thumbnail","13":"post-with-thumbnail-large"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nascimento...  - Crentassos Produ\u00e7\u00f5es Subversivas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nascimento...  - Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"og:description\" content=\"Hj n\u00e3o vim pra falar sobre teologia, miss\u00e3o, denunciar abusos nem nada do genero \u00c9 com muita alegria que a equipe do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html\" \/>\n<meta property=\"og:site_name\" content=\"Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/crentassos\" \/>\n<meta property=\"article:published_time\" content=\"2013-03-04T12:13:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/nascimento-novo-negocio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristiano Machado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@crentassos\" \/>\n<meta name=\"twitter:site\" content=\"@crentassos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristiano Machado\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/03\\\/nascimento.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/03\\\/nascimento.html\"},\"author\":{\"name\":\"Cristiano Machado\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/7ec3329a98c44e20ccd6cc2c9e18acbd\"},\"headline\":\"Nascimento&#8230;\",\"datePublished\":\"2013-03-04T12:13:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/03\\\/nascimento.html\"},\"wordCount\":84,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/03\\\/nascimento.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/nascimento-novo-negocio.jpg\",\"keywords\":[\"alegria\",\"danni distler\",\"nascimento\"],\"articleSection\":[\"Jab\u00e1\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/03\\\/nascimento.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/03\\\/nascimento.html\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/03\\\/nascimento.html\",\"name\":\"Nascimento... - Crentassos Produ\u00e7\u00f5es Subversivas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/03\\\/nascimento.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/03\\\/nascimento.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/nascimento-novo-negocio.jpg\",\"datePublished\":\"2013-03-04T12:13:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/03\\\/nascimento.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/03\\\/nascimento.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/03\\\/nascimento.html#primaryimage\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/nascimento-novo-negocio.jpg\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/nascimento-novo-negocio.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2013\\\/03\\\/nascimento.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nascimento&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"description\":\"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"width\":300,\"height\":300,\"caption\":\"Crentassos Produ\u00e7\u00f5es Subversivas\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/crentassos\",\"https:\\\/\\\/x.com\\\/crentassos\",\"https:\\\/\\\/www.instagram.com\\\/crentassos\",\"https:\\\/\\\/www.youtube.com\\\/crentassos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/7ec3329a98c44e20ccd6cc2c9e18acbd\",\"name\":\"Cristiano Machado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g\",\"caption\":\"Cristiano Machado\"},\"description\":\"Cristiano Machado \u00e9 o culpado pelo inicio do COLETIVO CRENTASSOS PRODU\u00c7\u00d5ES SUBVERSIVAS e atua como auxiliar de cirurgi\u00e3o barbeiro, tocando o bumbo, jogando malabares, preparando o elixir, costurando amputa\u00e7\u00f5es e demais atividades relacionadas \u00e0 sua ocupa\u00e7\u00e3o. Pensa n\u00e3o vida em forma de pergunta e nunca de resposta, e tem um profundo sentimento de gratid\u00e3o e amor por sua esposa e filha. Religi\u00e3o: Crist\u00e3o Protestante Reformando-se Estado Civil: Inteiramente apaixonado\",\"sameAs\":[\"http:\\\/\\\/crentassos.com.br\\\/blog\"],\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/author\\\/o_cristiano\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nascimento...  - Crentassos Produ\u00e7\u00f5es Subversivas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html","og_locale":"pt_BR","og_type":"article","og_title":"Nascimento...  - Crentassos Produ\u00e7\u00f5es Subversivas","og_description":"Hj n\u00e3o vim pra falar sobre teologia, miss\u00e3o, denunciar abusos nem nada do genero \u00c9 com muita alegria que a equipe do [&hellip;]","og_url":"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html","og_site_name":"Crentassos Produ\u00e7\u00f5es Subversivas","article_publisher":"http:\/\/www.facebook.com\/crentassos","article_published_time":"2013-03-04T12:13:48+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/nascimento-novo-negocio.jpg","type":"image\/jpeg"}],"author":"Cristiano Machado","twitter_card":"summary_large_image","twitter_creator":"@crentassos","twitter_site":"@crentassos","twitter_misc":{"Escrito por":"Cristiano Machado"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html#article","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html"},"author":{"name":"Cristiano Machado","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/7ec3329a98c44e20ccd6cc2c9e18acbd"},"headline":"Nascimento&#8230;","datePublished":"2013-03-04T12:13:48+00:00","mainEntityOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html"},"wordCount":84,"commentCount":1,"publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/nascimento-novo-negocio.jpg","keywords":["alegria","danni distler","nascimento"],"articleSection":["Jab\u00e1"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html","url":"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html","name":"Nascimento... - Crentassos Produ\u00e7\u00f5es Subversivas","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html#primaryimage"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/nascimento-novo-negocio.jpg","datePublished":"2013-03-04T12:13:48+00:00","breadcrumb":{"@id":"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html#primaryimage","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/nascimento-novo-negocio.jpg","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/nascimento-novo-negocio.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/crentassos.com.br\/blog\/2013\/03\/nascimento.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/crentassos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Nascimento&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/crentassos.com.br\/blog\/#website","url":"https:\/\/crentassos.com.br\/blog\/","name":"Crentassos Produ\u00e7\u00f5es Subversivas","description":"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos","publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crentassos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/crentassos.com.br\/blog\/#organization","name":"Crentassos Produ\u00e7\u00f5es Subversivas","url":"https:\/\/crentassos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","width":300,"height":300,"caption":"Crentassos Produ\u00e7\u00f5es Subversivas"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/crentassos","https:\/\/x.com\/crentassos","https:\/\/www.instagram.com\/crentassos","https:\/\/www.youtube.com\/crentassos"]},{"@type":"Person","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/7ec3329a98c44e20ccd6cc2c9e18acbd","name":"Cristiano Machado","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g","caption":"Cristiano Machado"},"description":"Cristiano Machado \u00e9 o culpado pelo inicio do COLETIVO CRENTASSOS PRODU\u00c7\u00d5ES SUBVERSIVAS e atua como auxiliar de cirurgi\u00e3o barbeiro, tocando o bumbo, jogando malabares, preparando o elixir, costurando amputa\u00e7\u00f5es e demais atividades relacionadas \u00e0 sua ocupa\u00e7\u00e3o. Pensa n\u00e3o vida em forma de pergunta e nunca de resposta, e tem um profundo sentimento de gratid\u00e3o e amor por sua esposa e filha. Religi\u00e3o: Crist\u00e3o Protestante Reformando-se Estado Civil: Inteiramente apaixonado","sameAs":["http:\/\/crentassos.com.br\/blog"],"url":"https:\/\/crentassos.com.br\/blog\/author\/o_cristiano"}]}},"_links":{"self":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/8678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=8678"}],"version-history":[{"count":1,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/8678\/revisions"}],"predecessor-version":[{"id":8680,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/8678\/revisions\/8680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media\/8679"}],"wp:attachment":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=8678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=8678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=8678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}