{"id":7371,"date":"2012-11-24T09:57:21","date_gmt":"2012-11-24T12:57:21","guid":{"rendered":"http:\/\/crentassos.com.br\/blog\/?p=7371"},"modified":"2012-11-20T10:01:57","modified_gmt":"2012-11-20T13:01:57","slug":"a-involucao-da-especie","status":"publish","type":"post","link":"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html","title":{"rendered":"A involu\u00e7\u00e3o da esp\u00e9cie."},"content":{"rendered":"<p>Acredito que, de certa forma a religi\u00e3o involuiu como forma segura de relacionamento com Deus. Mas n\u00e3o penso que isso tenho come\u00e7ado na ruptura do\u00a0 neopentecostal com a tradi\u00e7\u00e3o. A igreja tradicional j\u00e1 carrega em si essa involu\u00e7\u00e3o.\u00a0 Portanto me parece que em todas essas mudan\u00e7as, a igreja abre m\u00e3o de certas tradi\u00e7\u00f5es para subtitui-las por novas tend\u00eancias, muitas vezes mercadol\u00f3gicas.\u00a0 Por\u00e9m no fim, ser\u00e3o substitu\u00eddas novamente num ciclo onde Deus \u00e9 secund\u00e1rio\u00a0 pois a f\u00e9 n\u00e3o tem haver com Cristo mas sim com o que a igreja oferece em troca da devo\u00e7\u00e3o do fi\u00e9l. Ent\u00e3o hoje temos crist\u00e3o que n\u00e3o frequentam igrejas, ou frequentam igrejas que se mostram liberais ou que exigem menos. O fim do hall de membros da lugar ao \u201cp\u00fablico intinerante\u201d que busca um pouco de tudo para que no fim, fa\u00e7a sua pr\u00f3pria teologia de salva\u00e7\u00e3o e prosperidade pessoal.<\/p>\n<p>Ainda temos templos, cultos, liturgias, m\u00fasicas, apelos e estrat\u00e9gias. Isso permanece igual. Mas \u00e9 dentro de cada um desse itens que ocorre as mudan\u00e7as mais diversificadas. Templos para que? cultos para quem? estrat\u00e9gias para o que? m\u00fasicas sobre o que?.. enfim.. mesmo aqueles que n\u00e3o frequentam mais igrejas.. no fim.. constroem seus templos caseiros e criam suas vis\u00f5es eclesi\u00e1sticas. Nada mudou mas tudo est\u00e1 diferente. Na minha caminhada crist\u00e3, vejo igrejas tradicionais-pentecostais cantando m\u00fasicas neopentecoistais antes de um prega\u00e7\u00e3o fundamentalista para fi\u00e9s liberais.<\/p>\n<p>Tamb\u00e9m temos um n\u00famero grandes de analfabetos funcionais na massa crist\u00e3. Das periferias, das filas de aposentados, pobres mulheres solit\u00e1rias (n\u00e3o por falta de um homem mas por falta de um companheiro). Doentes em corredores do SUS. S\u00e3o essas pessoas que tem enchido igrejas que prometem riquezas, mas n\u00e3o garantem a vit\u00f3ria sobre os dem\u00f4nios, pois vai depender do\u00a0 pecado ou\u00a0 f\u00e9 do fi\u00e9l. A parte deles \u00e9 o show. A do crente \u00e9 pagar por isso. Como j\u00e1 disse, muda o espet\u00e1culo mas o circo \u00e9 o mesmo. Antigamente eram as bruxas queimadas, as indulg\u00eancias ou qualquer outra manipula\u00e7\u00e3o. O show da f\u00e9 segue firme.<\/p>\n<p>Quando afirmo que involuimos \u00e9 justamente por ver como crescemos em quantidade de evang\u00e9licos mas como junto com isso cresceu nossa irrelev\u00e2ncia na sociedade. Olhamos os dados do IBGE e louvamos a Deus porque somos um pa\u00eds de muitos evang\u00e9licos. Mas e dae? o que isso muda no mundo? o que muda em mim?<\/p>\n<p>Sou um cr\u00edtico do sistema capitalista. e por osmose me tornei um cr\u00edtico da institui\u00e7\u00e3o crist\u00e3. Por que ela diz que n\u00e3o devemos nos amoldar aos padr\u00f5es do mundo enquanto promove um congresso sobre estrat\u00e9gias empresariais para se ganhar almas pra Jesus. Marchamos pelas ruas ao som da nova m\u00fasicas gospel descart\u00e1vel da vez e achamos que isso \u00e9 evangelismo. Ou pior, sentamos a beira desse caminho e apontamos o dedo contra esses fariseus mercen\u00e1rios. Estamos todos confusos e nem sabemos mais se cremos na pregac\u00e3o que fazemos.<\/p>\n<p>\u00c9 um caos. Mas \u00e9 desse caos que estamos formando nossa identidade. nosso erros e acertos s\u00e3o postos lado a lado. Eu vejo por ae pessoas que antes bradavam contra as igrejas, pedindo perd\u00e3o e voltando ao caminho. Vejo l\u00edderes que contavam vantagens nas igrejas, trope\u00e7ando em suas pr\u00f3prias mentiras aos olhos dos fi\u00e9is. Eu vejo a promessa de restaura\u00e7\u00e3o da justi\u00e7a se concretizando. Eu vejo a Am\u00e9rica Latina descobrindo seu f\u00e9 como uma crian\u00e7a rec\u00e9m nascida descobre a pr\u00f3pria m\u00e3o.<\/p>\n<p>Mas \u00e9 claro que temos coisas boas. o neoevangelicalismo por exemplo (o Evangelho todo para o homem todo e para todos os homens. ) vem buscando seu espa\u00e7o na tentativa de responder a tantas loucuras feitas em nome da igreja. Temos pensadores, escritores, artistas (me ponho nessa categoria), pol\u00edticos. Todos querendo realinhar o pensamento \u201ccrist\u00e3o de igreja\u201d com o \u201cpensamento crist\u00e3o de Cristo\u201d.<\/p>\n<p>Meu consolo talvez seja saber que nossa teologia ainda est\u00e1 se formando , como magma em repouso.. meu \u00fanico receio \u00e9 que depois disso s\u00f3 pode virar pedra&#8230; e que Deus nos ajude para que seja a pedra angular da qual Jesus se refere no texto b\u00edblico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acredito que, de certa forma a religi\u00e3o involuiu como forma segura de relacionamento com Deus. Mas n\u00e3o penso que isso tenho come\u00e7ado [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":7372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[112],"tags":[1475,370,400,2017,31],"class_list":["post-7371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","tag-artigo","tag-crentassos","tag-danni-distler","tag-evolucao","tag-igreja","post-with-thumbnail","post-with-thumbnail-large"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A involu\u00e7\u00e3o da esp\u00e9cie. - Crentassos Produ\u00e7\u00f5es Subversivas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A involu\u00e7\u00e3o da esp\u00e9cie. - Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"og:description\" content=\"Acredito que, de certa forma a religi\u00e3o involuiu como forma segura de relacionamento com Deus. Mas n\u00e3o penso que isso tenho come\u00e7ado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html\" \/>\n<meta property=\"og:site_name\" content=\"Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/crentassos\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-24T12:57:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/images3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danni Distler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@crentassos\" \/>\n<meta name=\"twitter:site\" content=\"@crentassos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danni Distler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/11\\\/a-involucao-da-especie.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/11\\\/a-involucao-da-especie.html\"},\"author\":{\"name\":\"Danni Distler\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f28a0d59813bb7ad4666178ea4c2cfd5\"},\"headline\":\"A involu\u00e7\u00e3o da esp\u00e9cie.\",\"datePublished\":\"2012-11-24T12:57:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/11\\\/a-involucao-da-especie.html\"},\"wordCount\":738,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/11\\\/a-involucao-da-especie.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/images3.jpg\",\"keywords\":[\"artigo\",\"crentassos\",\"danni distler\",\"evolu\u00e7\u00e3o\",\"igreja\"],\"articleSection\":[\"Artigos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/11\\\/a-involucao-da-especie.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/11\\\/a-involucao-da-especie.html\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/11\\\/a-involucao-da-especie.html\",\"name\":\"A involu\u00e7\u00e3o da esp\u00e9cie. - Crentassos Produ\u00e7\u00f5es Subversivas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/11\\\/a-involucao-da-especie.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/11\\\/a-involucao-da-especie.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/images3.jpg\",\"datePublished\":\"2012-11-24T12:57:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/11\\\/a-involucao-da-especie.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/11\\\/a-involucao-da-especie.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/11\\\/a-involucao-da-especie.html#primaryimage\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/images3.jpg\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/images3.jpg\",\"width\":\"259\",\"height\":\"194\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/11\\\/a-involucao-da-especie.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A involu\u00e7\u00e3o da esp\u00e9cie.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"description\":\"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"width\":300,\"height\":300,\"caption\":\"Crentassos Produ\u00e7\u00f5es Subversivas\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/crentassos\",\"https:\\\/\\\/x.com\\\/crentassos\",\"https:\\\/\\\/www.instagram.com\\\/crentassos\",\"https:\\\/\\\/www.youtube.com\\\/crentassos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f28a0d59813bb7ad4666178ea4c2cfd5\",\"name\":\"Danni Distler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19f0efa0a4bbbe6d2b81b25c8aa112ade91c55ac3834001f3c0ac73e280de0cf?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19f0efa0a4bbbe6d2b81b25c8aa112ade91c55ac3834001f3c0ac73e280de0cf?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19f0efa0a4bbbe6d2b81b25c8aa112ade91c55ac3834001f3c0ac73e280de0cf?s=96&d=retro&r=g\",\"caption\":\"Danni Distler\"},\"description\":\"M\u00fasico, cantor, compositor, produtor musical, mission\u00e1rio contemporr\u00e2neo. Atua no meio musical h\u00e1 mais de 10 anos, viajando pelo Brasil e fora dele, atendendo a igrejas, eventos e fazendo shows em casa noturnas e bares.\",\"sameAs\":[\"http:\\\/\\\/www.dannidistler.com\"],\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/author\\\/dannidistler\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A involu\u00e7\u00e3o da esp\u00e9cie. - Crentassos Produ\u00e7\u00f5es Subversivas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html","og_locale":"pt_BR","og_type":"article","og_title":"A involu\u00e7\u00e3o da esp\u00e9cie. - Crentassos Produ\u00e7\u00f5es Subversivas","og_description":"Acredito que, de certa forma a religi\u00e3o involuiu como forma segura de relacionamento com Deus. Mas n\u00e3o penso que isso tenho come\u00e7ado [&hellip;]","og_url":"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html","og_site_name":"Crentassos Produ\u00e7\u00f5es Subversivas","article_publisher":"http:\/\/www.facebook.com\/crentassos","article_published_time":"2012-11-24T12:57:21+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/images3.jpg","type":"image\/jpeg"}],"author":"Danni Distler","twitter_card":"summary_large_image","twitter_creator":"@crentassos","twitter_site":"@crentassos","twitter_misc":{"Escrito por":"Danni Distler","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html#article","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html"},"author":{"name":"Danni Distler","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/f28a0d59813bb7ad4666178ea4c2cfd5"},"headline":"A involu\u00e7\u00e3o da esp\u00e9cie.","datePublished":"2012-11-24T12:57:21+00:00","mainEntityOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html"},"wordCount":738,"commentCount":1,"publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/images3.jpg","keywords":["artigo","crentassos","danni distler","evolu\u00e7\u00e3o","igreja"],"articleSection":["Artigos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html","url":"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html","name":"A involu\u00e7\u00e3o da esp\u00e9cie. - Crentassos Produ\u00e7\u00f5es Subversivas","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html#primaryimage"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/images3.jpg","datePublished":"2012-11-24T12:57:21+00:00","breadcrumb":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html#primaryimage","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/images3.jpg","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/images3.jpg","width":"259","height":"194"},{"@type":"BreadcrumbList","@id":"https:\/\/crentassos.com.br\/blog\/2012\/11\/a-involucao-da-especie.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/crentassos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"A involu\u00e7\u00e3o da esp\u00e9cie."}]},{"@type":"WebSite","@id":"https:\/\/crentassos.com.br\/blog\/#website","url":"https:\/\/crentassos.com.br\/blog\/","name":"Crentassos Produ\u00e7\u00f5es Subversivas","description":"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos","publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crentassos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/crentassos.com.br\/blog\/#organization","name":"Crentassos Produ\u00e7\u00f5es Subversivas","url":"https:\/\/crentassos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","width":300,"height":300,"caption":"Crentassos Produ\u00e7\u00f5es Subversivas"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/crentassos","https:\/\/x.com\/crentassos","https:\/\/www.instagram.com\/crentassos","https:\/\/www.youtube.com\/crentassos"]},{"@type":"Person","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/f28a0d59813bb7ad4666178ea4c2cfd5","name":"Danni Distler","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/19f0efa0a4bbbe6d2b81b25c8aa112ade91c55ac3834001f3c0ac73e280de0cf?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19f0efa0a4bbbe6d2b81b25c8aa112ade91c55ac3834001f3c0ac73e280de0cf?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19f0efa0a4bbbe6d2b81b25c8aa112ade91c55ac3834001f3c0ac73e280de0cf?s=96&d=retro&r=g","caption":"Danni Distler"},"description":"M\u00fasico, cantor, compositor, produtor musical, mission\u00e1rio contemporr\u00e2neo. Atua no meio musical h\u00e1 mais de 10 anos, viajando pelo Brasil e fora dele, atendendo a igrejas, eventos e fazendo shows em casa noturnas e bares.","sameAs":["http:\/\/www.dannidistler.com"],"url":"https:\/\/crentassos.com.br\/blog\/author\/dannidistler"}]}},"_links":{"self":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/7371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=7371"}],"version-history":[{"count":2,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/7371\/revisions"}],"predecessor-version":[{"id":7374,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/7371\/revisions\/7374"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media\/7372"}],"wp:attachment":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=7371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=7371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=7371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}