{"id":6754,"date":"2012-08-10T16:45:43","date_gmt":"2012-08-10T19:45:43","guid":{"rendered":"http:\/\/crentassos.com.br\/blog\/?p=6754"},"modified":"2012-08-10T16:46:57","modified_gmt":"2012-08-10T19:46:57","slug":"scholequee-introducao-ao-livro-de-jo-haja-paciencia-016","status":"publish","type":"post","link":"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html","title":{"rendered":"#ScholeQue\u00c9 \u2013 Introdu\u00e7\u00e3o ao livro de J\u00f3 \u2013 Haja paci\u00eancia #016"},"content":{"rendered":"<p><a href=\"http:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html\/016-16\" rel=\"attachment wp-att-6756\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-6756\" title=\"016.16\" src=\"http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/016.16-620x211.jpg\" alt=\"\" width=\"620\" height=\"211\" srcset=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/016.16-620x211.jpg 620w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/016.16-300x102.jpg 300w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/016.16.jpg 1841w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>O livro de J\u00f3 traduz para a vida pr\u00e1tica uma das mais antigas perguntas filos\u00f3ficas da humanidade: Por que sofremos? A busca racional pela compreens\u00e3o do sofrimento na vida do ser humano n\u00e3o sofreu modifica\u00e7\u00f5es nos \u00faltimos 5 mil anos e, al\u00e9m disso, tem sido um dos pilares sobre os quais os te\u00f3logos desenvolvem seus pensamentos.<\/p>\n<p>[tabs style=&#8221;default&#8221; title=&#8221;&#8221;] [tab title=&#8221;Introdu\u00e7\u00e3o&#8221;]<\/p>\n<p>O livro de J\u00f3 modifica a vis\u00e3o que temos da soberania divina, da arrog\u00e2ncia humana quando n\u00e3o sabe o quadro completo da situa\u00e7\u00e3o e da perspectiva b\u00edblica do sofrimento.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c9 poss\u00edvel que haja um trocadilho do nome do personagem principal do livro (<em>&#8216;iyy\u00f4b<\/em> no original hebraico) com o lamento de J\u00f3 em ser &#8220;inimigo&#8221; (<em>&#8216;\u00f4yeb<\/em> em hebraico) de Deus (Jo 13:24).<\/p>\n<p>&nbsp;<\/p>\n<p>Se o livro de J\u00f3 \u00e9 classificado como literatura de sabedoria \u00e9 poss\u00edvel, segundo os estudiosos, que os di\u00e1logos n\u00e3o tenham sido cita\u00e7\u00f5es literais, mas um ambiente criado para explicar as raz\u00f5es do sofrimento humano e a soberania divina na hist\u00f3ria.<\/p>\n<p>&nbsp;<\/p>\n<p>Apesar de n\u00e3o haver um consenso sobre a data dos acontecimentos, a narrativa de J\u00f3 \u00e9 uma das mais antigas do Oriente M\u00e9dio pelos seguintes fatores:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>A forma liter\u00e1ria do pr\u00f3logo &#8211; 1:1 &#8211; 2:13<\/li>\n<li>A forma liter\u00e1ria do ep\u00edlogo &#8211; 42:7-17<\/li>\n<li>N\u00e3o h\u00e1 men\u00e7\u00e3o de santu\u00e1rio ou sacerd\u00f3cio &#8211; J\u00f3 executava seu pr\u00f3prio sacrif\u00edcio (1:5)<\/li>\n<li>As posses de J\u00f3 s\u00e3o medidas por bois, ovelhas, jumentos e servos (1:3; compare com Gn. 12:16 e Gn. 32:5)<\/li>\n<li>Sua terra era amea\u00e7ada por ataques de tribos n\u00f4mades &#8211; 1:15-17<\/li>\n<li>N\u00e3o h\u00e1 men\u00e7\u00e3o da Lei ou da Alian\u00e7a<\/li>\n<li>Deus n\u00e3o \u00e9 mencionado como Jav\u00e9, <em>El Shaddai<\/em> \u00e9 mais frequente<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Embora a narrativa do livro seja contempor\u00e2nea ao per\u00edodo dos patriarcas (ver semelhan\u00e7as com G\u00eanesis), a maioria dos estudiosos concordam que a composi\u00e7\u00e3o do livro tenha sido por volta do s\u00e9culo VII, ou seja, antes do ex\u00edlio babil\u00f4nico, durante a monarquia dividida. Isto n\u00e3o representa um problema, pois a mensagem do livro de J\u00f3 ultrapassada as barreiras do tempo.<\/p>\n<p>[\/tab][tab title=&#8221;Estrutura&#8221;]<\/p>\n<p>O livro, embora esteja inclu\u00eddo na se\u00e7\u00e3o dos po\u00e9ticos, possui diversas formas liter\u00e1rias:<\/p>\n<ul>\n<li>Di\u00e1logos &#8211; Caps. 4 a 27<\/li>\n<li>Mon\u00f3logo &#8211; Cap. 3<\/li>\n<li>Discursos &#8211; Caps. 29 a 41<\/li>\n<li>Narrativas &#8211; Caps. 1 e 2<\/li>\n<li>Hino &#8211; Cap. 28<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>O livro de J\u00f3 pode ser dividido da seguinte forma:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Pr\u00f3logo (prosa) &#8211; 1 &#8211; 2<\/li>\n<li>Discursos (poesia) &#8211; 3 &#8211; 42:6\n<ul>\n<li>Di\u00e1logo &#8211; 3 &#8211; 28<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>\u25cf\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Lamento de J\u00f3 &#8211; 3<\/p>\n<p>\u25cf\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Di\u00e1logo entre J\u00f3 e seus amigos &#8211; 4 &#8211; 27<\/p>\n<p>\u25cf\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Poema da sabedoria &#8211; 28<\/p>\n<ul>\n<li>Mon\u00f3logo 29 &#8211; 42:6<\/li>\n<\/ul>\n<p>\u25cf\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 J\u00f3 se diz inocente &#8211; 29 &#8211; 31<\/p>\n<p>\u25cf\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Discurso de Eli\u00fa &#8211; 32 &#8211; 37<\/p>\n<p>\u25cf\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Discursos de Jav\u00e9 &#8211; 38 &#8211; 42:6<\/p>\n<ul>\n<li>Ep\u00edlogo (prosa) &#8211; 42:7-17<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>O livro de J\u00f3 \u00e9 estruturado para que o leitor conhe\u00e7a os personagens e alguns detalhes que eles mesmos desconhecem, como por exemplo, o desafio de Satan\u00e1s a Jav\u00e9. Desta forma, o leitor sabe de antem\u00e3o que os amigos de J\u00f3 est\u00e3o equivocados a seu respeito.<\/p>\n<p>O lamento de J\u00f3 no cap\u00edtulo 3 d\u00e1 in\u00edcio ao ciclo de di\u00e1logos que vai do Cap. 4 ao 27. Nestes di\u00e1logos os amigos de J\u00f3 tornam-se cada vez mais contr\u00e1rios a ele, e, embora a teologia desses amigos n\u00e3o esteja incorreta, \u00e9 fato que seu papel como consolador fica muito aqu\u00e9m do esperado. A teologia tradicional da \u00e9poca dizia que o justo prospera e o \u00edmpio sofre. Este \u00e9 a chamada\u00a0 Justi\u00e7a Retirbutiva, muito afirmada nos livros de Salmos e Prov\u00e9rbios. Os amigos de J\u00f3 utilizam-se da dedu\u00e7\u00e3o deste princ\u00edpio para o acusarem.<\/p>\n<p>&nbsp;<\/p>\n<p>J\u00f3 afirma que este Princ\u00edpio pode ter sua exce\u00e7\u00e3o, com a prosperidade do \u00edmpio e o sofrimento do justo, mas desconfia da justi\u00e7a divina e passa a colocar Deus no banco dos r\u00e9us. As respostas dos amigos de J\u00f3 apresentam a filosofia da \u00e9poca, isto \u00e9, desistir de entender a vida e confessar crimes n\u00e3o cometidos para acalmar a divindade. O trecho de 27:1-6 mostra que a integridade de J\u00f3 se manteve justamente por se recusar a fazer isso. Ao agir desta maneira J\u00f3 recusou o tratamento que outros povos davam \u00e0s divindades pag\u00e3s, que faziam falsas confiss\u00f5es para obter favores e ben\u00e7\u00e3os.<\/p>\n<p>&nbsp;<\/p>\n<p>O di\u00e1logo \u00e9 quebrado pelo hino \u00e0 Sabedoria no cap\u00edtulo 28, que sugere que a verdadeira sabedoria ainda n\u00e3o se manigestou. Este hino mostra Deus como criador da Sabedoria\u00a0 e ensina que a sabedoria humana s\u00f3 pode vir do temor do Senhor. Isso introduz o trecho dos discursos, ou mon\u00f3logos e indica a conclus\u00e3o do dilema.<\/p>\n<p>&nbsp;<\/p>\n<p>O primeiro discurso apresenta o lamento de J\u00f3 ao recordar sua antiga posi\u00e7\u00e3o e ver sua situa\u00e7\u00e3o atual. O juramento que ele faz tem a inten\u00e7\u00e3o de for\u00e7ar Deus a agir, isto \u00e9, se ele for culpado de qualquer coisa citada no juramento Deus deveria executar seu ju\u00edzo contra ele, portanto o sil\u00eancio de Deus serviria com sua justifica\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>O segundo discurso mant\u00e9m o suspense em rela\u00e7\u00e3o \u00e0 resposta de Deus a J\u00f3. Aqui Eli\u00fa expoe de forma mais filos\u00f3fica a quest\u00e3o do sofrimento humano, que pode, al\u00e9m de punitivo, ser preventivo, isto \u00e9, Deus, por meio do sofrimento, fazia J\u00f3 manter-se no caminho correto. Desta forma, o sofrimento pode ser uma maneira de Deus demonstrar sua miseric\u00f3rdia.<\/p>\n<p>&nbsp;<\/p>\n<p>O terceiro discurso, quando Deus toma a palavra, \u00e9 caracterizado pela aus\u00eancia das respostas esperadas. Desconsidera a queixa de J\u00f3, e n\u00e3o responde ao juramento de inoc\u00eancia. Deus muda o rumo do discurso de sua justi\u00e7a para sua sabedoria, pois Deus \u00e9 respons\u00e1vel pela cria\u00e7\u00e3o do mundo e sua sustenta\u00e7\u00e3o soberana. Deus diz que o mundo n\u00e3o foi criado pelo principio da retribui\u00e7\u00e3o (38:26), inclusive desafia J\u00f3 a criar um mundo com este princ\u00edpio como fundamento (40:10-14). A conclus\u00e3o \u00e9 que as causas do sofrimento n\u00e3o s\u00e3o coerentes e ningu\u00e9m \u00e9 s\u00e1bio o suficiente para questionar a justi\u00e7a divina.<\/p>\n<p>&nbsp;<\/p>\n<p>No ep\u00edlogo a prosperidade de J\u00f3 n\u00e3o se d\u00e1 de forma gratuita, mas \u00e9 uma resposta a Satan\u00e1s de que Deus continuar\u00e1 intervindo em favor do justo. Os amigos de J\u00f3 s\u00e3o repreendidos, n\u00e3o por se posicionarem contra J\u00f3, mas por n\u00e3o falar corretamente a respeito de Deus (42:7-8). Mesmo tendo sua vida restaurada, J\u00f3 n\u00e3o tem a explica\u00e7\u00e3o do seu sofrimento, pois, para o livro o mais importante n\u00e3o \u00e9 o motivo do sofrimento, mas as a\u00e7\u00f5es e os procedimentos de Deus. Para o leitor, J\u00f3 n\u00e3o \u00e9 culpado de nada, e foi justificado n\u00e3o por causa do seu sofrimento, mas pela demonstra\u00e7\u00e3o de grande sabedoria.[\/tab][tab title=&#8221;Prop\u00f3sito e conte\u00fado&#8221;]<\/p>\n<p>O livro de J\u00f3 trata\u00a0 dos seguintes princ\u00edpios:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>N\u00e3o s\u00e3o apenas os \u00edmpios que sofrem<\/li>\n<li>A justi\u00e7a pode ser conhecida por meio da sabedoria de Deus<\/li>\n<li>A justi\u00e7a de Deus vai al\u00e9m de senten\u00e7as simples como o princ\u00edpio da retribui\u00e7\u00e3o<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>O prop\u00f3sito do livro de J\u00f3 \u00e9 analisar o tratamento que Deus d\u00e1 aos justos e \u00edmpios. De acordo com o desafio de Satan\u00e1s, as ben\u00e7\u00e3os n\u00e3o produzem verdadeiros justos, pois esses s\u00f3 s\u00e3o \u00edntegros por causa das recompensas que recebem, ou seja, n\u00e3o existe amor \u00e0 integridade por si mesma. Outro aspecto \u00e9 o julgamento que J\u00f3 faz de Deus ao permitir que o justo sofra, isto \u00e9, o procedimento de Deus est\u00e1 sendo criticado.<\/p>\n<p>&nbsp;<\/p>\n<p>Para cumprir este prop\u00f3sito o livro descarta a tentativa de manipula\u00e7\u00e3o da divindade dos antigos povos pag\u00e3os do Oriente M\u00e9dio e a filosofia rasa dos amigos de J\u00f3. Uma vez que o leitor estava ciente da inoc\u00eancia de J\u00f3 desde o in\u00edcio n\u00e3o importa muito o fato de Deus te-lo inocentado. O importante \u00e9 que J\u00f3 manteve sua integridade para com Deus, mesmo quando n\u00e3o foi aben\u00e7oado por isso.<\/p>\n<p>&nbsp;<\/p>\n<p>A mensagem do livro \u00e9 que Deus n\u00e3o est\u00e1 obrigado a aben\u00e7oar o justo, mas a justi\u00e7a divina \u00e9 deduzida de sua sabedoria, que est\u00e1 al\u00e9m de todo conhecimento humano.<\/p>\n<p>&nbsp;<\/p>\n<p><em>O principio da retribui\u00e7\u00e3o: Primeira Parte<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>O princ\u00edpio da retribui\u00e7\u00e3o foi o fundamento para os debates e di\u00e1logos na hist\u00f3ria de J\u00f3. Era um sistema de pensamento muito simplificado que determinava que o justo sempre prosperaria e o \u00edmpio sempre sofreria.<\/p>\n<p>&nbsp;<\/p>\n<p>Este sistema de pensamento dominava a cultura israelita, mas na pr\u00e1tica, a teoria era outra. Basta lermos os primeiros versos do Salmo 37 para verificarmos que nem sempre este sistema de pensamento funcionava adequadamente. Para o israelita isso era particularmente embara\u00e7oso, pois, se havia um \u00fanico Deus soberano, toda justi\u00e7a, bem como todo sofrimento, s\u00f3 poderia vir dele. Al\u00e9m disso, Deus era plenamente justo, portanto o sofrimento deveria ter uma explica\u00e7\u00e3o l\u00f3gica e v\u00e1lida. E Deus, sendo plenamente justo, o sofrimento deveria ser proporcional \u00e0 injusti\u00e7a do homem, e a prosperidade proporcional \u00e0 sua virtude.<\/p>\n<p>&nbsp;<\/p>\n<p>No livro de J\u00f3 todos os personagens vivem sob este sistema e n\u00e3o h\u00e1 outra maneira de viver. O livro de J\u00f3 pretende mostrar que a conclus\u00e3o absolutamente certa do princ\u00edpio da retribui\u00e7\u00e3o est\u00e1 equivocado, pois n\u00e3o \u00e9 poss\u00edvel saber com exatid\u00e3o quando acontecer\u00e1. Portanto, a conclus\u00e3o de que o justo sempre prosperar\u00e1 e o \u00edmpio sempre sofrer\u00e1 deve ser rejeitada.<\/p>\n<p>&nbsp;<\/p>\n<p>O princ\u00edpio da retribui\u00e7\u00e3o deve ser entendido a partir de Deus e n\u00e3o do homem. A Teologia do Antigo Testamento afirma in\u00fameras vezes que Deus far\u00e1 prosperar o justo e punir\u00e1 o \u00edmpio, entretanto este princ\u00edpio n\u00e3o deve ser usado para exigir a a\u00e7\u00e3o imediata de Deus, e nem deve ser usada como fundamento para entender o sucesso ou sofrimento individuais. Nosso consolo est\u00e1 fundamentado na soberania e sabedoria de Deus.<\/p>\n<p>&nbsp;<\/p>\n<p><em>A soberania de Deus, sua justi\u00e7a e sabedoria<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Na literatura de sabedoria em geral, e tamb\u00e9m no livro de J\u00f3, a sabedoria, justi\u00e7a e soberania de Deus s\u00e3o amplamente discutidas. Embora o livro de J\u00f3 n\u00e3o esteja intimamente ligado com a Alian\u00e7a podemos estabelecer um paralelo com os conceitos teol\u00f3gicos da Alian\u00e7a j\u00e1 apresentados em outras ocasi\u00f5es tais como: a lealdade, a compaix\u00e3o e a bondade (\u00cax. 34:6; Jl. 2:13; Jn. 4:2; Ne. 9:17; Sl. 86:15; 103:8; 145:8).<\/p>\n<p>&nbsp;<\/p>\n<p>O livro de J\u00f3 nos mostra que a onisci\u00eancia de Deus \u00e9 apenas uma parte de sua sabedoria infinita, a onipot\u00eancia \u00e9 somente um aspecto de sua soberania ilimitada e a miseric\u00f3rdia \u00e9 entendida como a sua justi\u00e7a. Estas categorias maiores nos ajudam a entender quem Deus \u00e9, do que somente aquilo que ele pode fazer por algu\u00e9m.<\/p>\n<p>&nbsp;<\/p>\n<p><em>O mediador<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Em v\u00e1rios momentos do livro, J\u00f3 parece crer na interven\u00e7\u00e3o de um advogado, um redentor (5:1; 9:33; 16:18-22; 19:25-27; 33:23). Alguns acreditam que se trata da cren\u00e7a na ressurrei\u00e7\u00e3o, outros entendem que J\u00f3 ter\u00e1 a justi\u00e7a aplicada ap\u00f3s a morte, e outros ainda creem que se trata de uma previs\u00e3o messi\u00e2nica.<\/p>\n<p>&nbsp;<\/p>\n<p>Independente das variadas posi\u00e7\u00f5es, o papel do mediador parece claro. A maioria cre que J\u00f3 espera pelo pr\u00f3prio Deus, por\u00e9m, algumas defini\u00e7\u00f5es parecem apontar para algum parente distante que viria ajud\u00e1-lo (tal qual o remidor estudado em Rute).<\/p>\n<p>&nbsp;<\/p>\n<p>Entretanto, o tema do redentor aparece somente nos di\u00e1logos, e parece n\u00e3o ter um papel fundamental no fim da trama, quando J\u00f3, diante da sabedoria de Deus tem a necessidade de um redentor eliminada diante da restaura\u00e7\u00e3o que Deus promovera.[\/tab][\/tabs]<\/p>\n<p>[button size=&#8221;small&#8221; color=&#8221;blue&#8221; style=&#8221;download&#8221; new_window=&#8221;true&#8221; link=&#8221;http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/017-Introdu\u00e7\u00e3o-J\u00f3-Crentassos.pdf&#8221;]Download (PDF)[\/button]<\/p>\n<p><strong><em>Para ler o post original no blog do autor, clique no banner<\/em><\/strong><\/p>\n<p><a href=\"http:\/\/wp.me\/pDkVr-eN\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" title=\"Milhoranza\" src=\"http:\/\/alexandremilhoranza.files.wordpress.com\/2011\/10\/banner.gif\" alt=\"Milhoranza\" width=\"120\" height=\"60\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O livro de J\u00f3 traduz para a vida pr\u00e1tica uma das mais antigas perguntas filos\u00f3ficas da humanidade: Por que sofremos? A [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6756,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1577],"tags":[1608,197,72,1818,975,1621],"class_list":["post-6754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schole-que-e-crentassos","tag-alianca","tag-antigo-testamento","tag-biblia","tag-curso-teologico","tag-promessa","tag-teologia-antigo-testamento","post-with-thumbnail","post-with-thumbnail-large"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#ScholeQue\u00c9 \u2013 Introdu\u00e7\u00e3o ao livro de J\u00f3 \u2013 Haja paci\u00eancia #016 - Crentassos Produ\u00e7\u00f5es Subversivas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#ScholeQue\u00c9 \u2013 Introdu\u00e7\u00e3o ao livro de J\u00f3 \u2013 Haja paci\u00eancia #016 - Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"og:description\" content=\"&nbsp; O livro de J\u00f3 traduz para a vida pr\u00e1tica uma das mais antigas perguntas filos\u00f3ficas da humanidade: Por que sofremos? A [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html\" \/>\n<meta property=\"og:site_name\" content=\"Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/crentassos\" \/>\n<meta property=\"article:published_time\" content=\"2012-08-10T19:45:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-08-10T19:46:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/016.16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1841\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexandre Milhoranza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@crentassos\" \/>\n<meta name=\"twitter:site\" content=\"@crentassos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Milhoranza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/08\\\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/08\\\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html\"},\"author\":{\"name\":\"Alexandre Milhoranza\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/3a9be2a7c2c83a923f7ae8bd0489dc3f\"},\"headline\":\"#ScholeQue\u00c9 \u2013 Introdu\u00e7\u00e3o ao livro de J\u00f3 \u2013 Haja paci\u00eancia #016\",\"datePublished\":\"2012-08-10T19:45:43+00:00\",\"dateModified\":\"2012-08-10T19:46:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/08\\\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html\"},\"wordCount\":2040,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/08\\\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/016.16.jpg\",\"keywords\":[\"alian\u00e7a\",\"Antigo Testamento\",\"biblia\",\"curso teol\u00f3gico\",\"Promessa\",\"Teologia Antigo Testamento\"],\"articleSection\":[\"Schol\u00e9 que \u00e9 Crentassos?\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/08\\\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/08\\\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/08\\\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html\",\"name\":\"#ScholeQue\u00c9 \u2013 Introdu\u00e7\u00e3o ao livro de J\u00f3 \u2013 Haja paci\u00eancia #016 - Crentassos Produ\u00e7\u00f5es Subversivas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/08\\\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/08\\\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/016.16.jpg\",\"datePublished\":\"2012-08-10T19:45:43+00:00\",\"dateModified\":\"2012-08-10T19:46:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/08\\\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/08\\\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/08\\\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#primaryimage\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/016.16.jpg\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/016.16.jpg\",\"width\":\"1841\",\"height\":\"628\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/08\\\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#ScholeQue\u00c9 \u2013 Introdu\u00e7\u00e3o ao livro de J\u00f3 \u2013 Haja paci\u00eancia #016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"description\":\"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"width\":300,\"height\":300,\"caption\":\"Crentassos Produ\u00e7\u00f5es Subversivas\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/crentassos\",\"https:\\\/\\\/x.com\\\/crentassos\",\"https:\\\/\\\/www.instagram.com\\\/crentassos\",\"https:\\\/\\\/www.youtube.com\\\/crentassos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/3a9be2a7c2c83a923f7ae8bd0489dc3f\",\"name\":\"Alexandre Milhoranza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17f80a1c8a34962bececa293e2fb3de9b9a96197bc1cb7595d98fbb579662872?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17f80a1c8a34962bececa293e2fb3de9b9a96197bc1cb7595d98fbb579662872?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17f80a1c8a34962bececa293e2fb3de9b9a96197bc1cb7595d98fbb579662872?s=96&d=retro&r=g\",\"caption\":\"Alexandre Milhoranza\"},\"description\":\"Alexandre Milhoranza \u00e9 analista de sistemas e bacharel em teologia pela Faculdade Teol\u00f3gica Batista de S\u00e3o Paulo, Mestre e doutorando em Teologia pelo Instituto Protestante de Teologia em Montpellier, Fran\u00e7a. Tamb\u00e9m \u00e9 pastor auxiliar na Igreja Evang\u00e9lica Batista em Montpellier, Fran\u00e7a. Sempre insiste em fugir das tarefas que Deus coloca em sua vida. Muito bem casado com a Ana Claudia e pai da B\u00e1rbara e do Eduardo, seus mini fil\u00f3sofos de plant\u00e3o.\",\"sameAs\":[\"http:\\\/\\\/www.alexandremilhoranza.com\"],\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/author\\\/milhoranza\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#ScholeQue\u00c9 \u2013 Introdu\u00e7\u00e3o ao livro de J\u00f3 \u2013 Haja paci\u00eancia #016 - Crentassos Produ\u00e7\u00f5es Subversivas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html","og_locale":"pt_BR","og_type":"article","og_title":"#ScholeQue\u00c9 \u2013 Introdu\u00e7\u00e3o ao livro de J\u00f3 \u2013 Haja paci\u00eancia #016 - Crentassos Produ\u00e7\u00f5es Subversivas","og_description":"&nbsp; O livro de J\u00f3 traduz para a vida pr\u00e1tica uma das mais antigas perguntas filos\u00f3ficas da humanidade: Por que sofremos? A [&hellip;]","og_url":"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html","og_site_name":"Crentassos Produ\u00e7\u00f5es Subversivas","article_publisher":"http:\/\/www.facebook.com\/crentassos","article_published_time":"2012-08-10T19:45:43+00:00","article_modified_time":"2012-08-10T19:46:57+00:00","og_image":[{"width":1841,"height":628,"url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/016.16.jpg","type":"image\/jpeg"}],"author":"Alexandre Milhoranza","twitter_card":"summary_large_image","twitter_creator":"@crentassos","twitter_site":"@crentassos","twitter_misc":{"Escrito por":"Alexandre Milhoranza","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#article","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html"},"author":{"name":"Alexandre Milhoranza","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/3a9be2a7c2c83a923f7ae8bd0489dc3f"},"headline":"#ScholeQue\u00c9 \u2013 Introdu\u00e7\u00e3o ao livro de J\u00f3 \u2013 Haja paci\u00eancia #016","datePublished":"2012-08-10T19:45:43+00:00","dateModified":"2012-08-10T19:46:57+00:00","mainEntityOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html"},"wordCount":2040,"commentCount":4,"publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/016.16.jpg","keywords":["alian\u00e7a","Antigo Testamento","biblia","curso teol\u00f3gico","Promessa","Teologia Antigo Testamento"],"articleSection":["Schol\u00e9 que \u00e9 Crentassos?"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html","url":"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html","name":"#ScholeQue\u00c9 \u2013 Introdu\u00e7\u00e3o ao livro de J\u00f3 \u2013 Haja paci\u00eancia #016 - Crentassos Produ\u00e7\u00f5es Subversivas","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#primaryimage"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/016.16.jpg","datePublished":"2012-08-10T19:45:43+00:00","dateModified":"2012-08-10T19:46:57+00:00","breadcrumb":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#primaryimage","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/016.16.jpg","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/016.16.jpg","width":"1841","height":"628"},{"@type":"BreadcrumbList","@id":"https:\/\/crentassos.com.br\/blog\/2012\/08\/scholequee-introducao-ao-livro-de-jo-haja-paciencia-016.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/crentassos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"#ScholeQue\u00c9 \u2013 Introdu\u00e7\u00e3o ao livro de J\u00f3 \u2013 Haja paci\u00eancia #016"}]},{"@type":"WebSite","@id":"https:\/\/crentassos.com.br\/blog\/#website","url":"https:\/\/crentassos.com.br\/blog\/","name":"Crentassos Produ\u00e7\u00f5es Subversivas","description":"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos","publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crentassos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/crentassos.com.br\/blog\/#organization","name":"Crentassos Produ\u00e7\u00f5es Subversivas","url":"https:\/\/crentassos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","width":300,"height":300,"caption":"Crentassos Produ\u00e7\u00f5es Subversivas"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/crentassos","https:\/\/x.com\/crentassos","https:\/\/www.instagram.com\/crentassos","https:\/\/www.youtube.com\/crentassos"]},{"@type":"Person","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/3a9be2a7c2c83a923f7ae8bd0489dc3f","name":"Alexandre Milhoranza","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/17f80a1c8a34962bececa293e2fb3de9b9a96197bc1cb7595d98fbb579662872?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17f80a1c8a34962bececa293e2fb3de9b9a96197bc1cb7595d98fbb579662872?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17f80a1c8a34962bececa293e2fb3de9b9a96197bc1cb7595d98fbb579662872?s=96&d=retro&r=g","caption":"Alexandre Milhoranza"},"description":"Alexandre Milhoranza \u00e9 analista de sistemas e bacharel em teologia pela Faculdade Teol\u00f3gica Batista de S\u00e3o Paulo, Mestre e doutorando em Teologia pelo Instituto Protestante de Teologia em Montpellier, Fran\u00e7a. Tamb\u00e9m \u00e9 pastor auxiliar na Igreja Evang\u00e9lica Batista em Montpellier, Fran\u00e7a. Sempre insiste em fugir das tarefas que Deus coloca em sua vida. Muito bem casado com a Ana Claudia e pai da B\u00e1rbara e do Eduardo, seus mini fil\u00f3sofos de plant\u00e3o.","sameAs":["http:\/\/www.alexandremilhoranza.com"],"url":"https:\/\/crentassos.com.br\/blog\/author\/milhoranza"}]}},"_links":{"self":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/6754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=6754"}],"version-history":[{"count":7,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/6754\/revisions"}],"predecessor-version":[{"id":6762,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/6754\/revisions\/6762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media\/6756"}],"wp:attachment":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=6754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=6754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=6754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}