{"id":6370,"date":"2012-05-29T18:03:09","date_gmt":"2012-05-29T21:03:09","guid":{"rendered":"http:\/\/crentassos.com.br\/blog\/?p=6370"},"modified":"2012-05-29T18:03:09","modified_gmt":"2012-05-29T21:03:09","slug":"cartao-ore-e-envie-igrejas-eco-cidadas","status":"publish","type":"post","link":"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html","title":{"rendered":"Cart\u00e3o Ore e Envie&#8230; Igrejas ECO Cidad\u00e3s!"},"content":{"rendered":"<h3 style=\"text-align: justify;\">O que \u00e9?<img loading=\"lazy\" decoding=\"async\" class=\"alignright size-large wp-image-6371\" title=\"Igreja Eco Cidad\u00e3s\" src=\"http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/logo-igrejasecocidadas-png2-620x335.png\" alt=\"\" width=\"365\" height=\"197\" srcset=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/logo-igrejasecocidadas-png2-620x335.png 620w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/logo-igrejasecocidadas-png2-300x162.png 300w\" sizes=\"auto, (max-width: 365px) 100vw, 365px\" \/><\/h3>\n<p style=\"text-align: justify;\">Cart\u00e3o Ore e Envie \u00e9 uma ferramenta de informa\u00e7\u00e3o, reflex\u00e3o, ora\u00e7\u00e3o e a\u00e7\u00e3o da peti\u00e7\u00e3o\u00a0<em>\u201cFALE por um mundo justo e sustent\u00e1vel\u201d <\/em>das <a href=\"http:\/\/ultimato.com.br\/sites\/igrejasecocidadas\/\" target=\"_blank\">Igrejas Ecocidad\u00e3s<\/a>. Por meio dele os crist\u00e3os poder\u00e3o reivindicar um maior comprometimento na defesa do meio ambiente e erradica\u00e7\u00e3o da pobreza \u00e0 nossa Excelent\u00edssima Presidenta Dilma Roussef.<\/p>\n<h3 style=\"text-align: justify;\">Como participar da peti\u00e7\u00e3o?<\/h3>\n<ul style=\"text-align: justify;\">\n<li><strong>BAIXE <\/strong>o\u00a0<strong><a href=\"http:\/\/ultimato.com.br\/sites\/igrejasecocidadas\/files\/2012\/04\/cart%C3%A3o-Ore-e-Envie.pdf\" target=\"_blank\">cart\u00e3o<\/a><\/strong>, <strong>IMPRIMA<\/strong>-o em 1 \u00fanica folha (impress\u00e3o frente e verso), assine e <strong>ENVIE<\/strong>-o \u00e0 nossa Presidenta.<\/li>\n<li>Ou <strong>ASSINE<\/strong>\u00a0a peti\u00e7\u00e3o\u00a0<em>\u201cFALE por um mundo justo e sustent\u00e1vel\u201d <\/em><a href=\"http:\/\/ultimato.com.br\/sites\/igrejasecocidadas\/assine-a-peticao-online\/\" target=\"_blank\">ONLINE<\/a> e depois <strong>COMPARTILHE<\/strong>-a em seu Facebook e Twitter.<\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\">Quer nos ajudar ainda mais?<\/h3>\n<p style=\"text-align: justify;\"><strong>BAIXE <\/strong>a<strong>\u00a0<a href=\"http:\/\/ultimato.com.br\/sites\/igrejasecocidadas\/files\/2012\/04\/Abaixo-assinado-campanha.pdf\" target=\"_blank\">peti\u00e7\u00e3o<\/a><\/strong>, <strong>IMPRIMA<\/strong>-a, <strong>COLETE<\/strong>\u00a0assinaturas de amigos, familiares e em sua igreja; e depois nos <strong>DEVOLVA\u00a0<\/strong>pelos Correios (at\u00e9 dia 01 de junho) ou por email (igrejas.ecocidadas@gmail.com). Endere\u00e7o para envio: Caixa Posta 546, CEP 13330-972, Indaiatuba, SP.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O que \u00e9? Cart\u00e3o Ore e Envie \u00e9 uma ferramenta de informa\u00e7\u00e3o, reflex\u00e3o, ora\u00e7\u00e3o e a\u00e7\u00e3o da peti\u00e7\u00e3o\u00a0\u201cFALE por um mundo justo [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":6371,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[112],"tags":[],"class_list":["post-6370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","post-with-thumbnail","post-with-thumbnail-large"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cart\u00e3o Ore e Envie... Igrejas ECO Cidad\u00e3s! - Crentassos Produ\u00e7\u00f5es Subversivas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cart\u00e3o Ore e Envie... Igrejas ECO Cidad\u00e3s! - Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"og:description\" content=\"O que \u00e9? Cart\u00e3o Ore e Envie \u00e9 uma ferramenta de informa\u00e7\u00e3o, reflex\u00e3o, ora\u00e7\u00e3o e a\u00e7\u00e3o da peti\u00e7\u00e3o\u00a0\u201cFALE por um mundo justo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html\" \/>\n<meta property=\"og:site_name\" content=\"Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/crentassos\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-29T21:03:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/logo-igrejasecocidadas-png2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"3095\" \/>\n\t<meta property=\"og:image:height\" content=\"1674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Cristiano Machado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@crentassos\" \/>\n<meta name=\"twitter:site\" content=\"@crentassos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristiano Machado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/05\\\/cartao-ore-e-envie-igrejas-eco-cidadas.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/05\\\/cartao-ore-e-envie-igrejas-eco-cidadas.html\"},\"author\":{\"name\":\"Cristiano Machado\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/7ec3329a98c44e20ccd6cc2c9e18acbd\"},\"headline\":\"Cart\u00e3o Ore e Envie&#8230; Igrejas ECO Cidad\u00e3s!\",\"datePublished\":\"2012-05-29T21:03:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/05\\\/cartao-ore-e-envie-igrejas-eco-cidadas.html\"},\"wordCount\":162,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/05\\\/cartao-ore-e-envie-igrejas-eco-cidadas.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/logo-igrejasecocidadas-png2.png\",\"articleSection\":[\"Artigos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/05\\\/cartao-ore-e-envie-igrejas-eco-cidadas.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/05\\\/cartao-ore-e-envie-igrejas-eco-cidadas.html\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/05\\\/cartao-ore-e-envie-igrejas-eco-cidadas.html\",\"name\":\"Cart\u00e3o Ore e Envie... Igrejas ECO Cidad\u00e3s! - Crentassos Produ\u00e7\u00f5es Subversivas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/05\\\/cartao-ore-e-envie-igrejas-eco-cidadas.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/05\\\/cartao-ore-e-envie-igrejas-eco-cidadas.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/logo-igrejasecocidadas-png2.png\",\"datePublished\":\"2012-05-29T21:03:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/05\\\/cartao-ore-e-envie-igrejas-eco-cidadas.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/05\\\/cartao-ore-e-envie-igrejas-eco-cidadas.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/05\\\/cartao-ore-e-envie-igrejas-eco-cidadas.html#primaryimage\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/logo-igrejasecocidadas-png2.png\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/logo-igrejasecocidadas-png2.png\",\"width\":\"3095\",\"height\":\"1674\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/05\\\/cartao-ore-e-envie-igrejas-eco-cidadas.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cart\u00e3o Ore e Envie&#8230; Igrejas ECO Cidad\u00e3s!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"description\":\"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"width\":300,\"height\":300,\"caption\":\"Crentassos Produ\u00e7\u00f5es Subversivas\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/crentassos\",\"https:\\\/\\\/x.com\\\/crentassos\",\"https:\\\/\\\/www.instagram.com\\\/crentassos\",\"https:\\\/\\\/www.youtube.com\\\/crentassos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/7ec3329a98c44e20ccd6cc2c9e18acbd\",\"name\":\"Cristiano Machado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g\",\"caption\":\"Cristiano Machado\"},\"description\":\"Cristiano Machado \u00e9 o culpado pelo inicio do COLETIVO CRENTASSOS PRODU\u00c7\u00d5ES SUBVERSIVAS e atua como auxiliar de cirurgi\u00e3o barbeiro, tocando o bumbo, jogando malabares, preparando o elixir, costurando amputa\u00e7\u00f5es e demais atividades relacionadas \u00e0 sua ocupa\u00e7\u00e3o. Pensa n\u00e3o vida em forma de pergunta e nunca de resposta, e tem um profundo sentimento de gratid\u00e3o e amor por sua esposa e filha. Religi\u00e3o: Crist\u00e3o Protestante Reformando-se Estado Civil: Inteiramente apaixonado\",\"sameAs\":[\"http:\\\/\\\/crentassos.com.br\\\/blog\"],\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/author\\\/o_cristiano\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cart\u00e3o Ore e Envie... Igrejas ECO Cidad\u00e3s! - Crentassos Produ\u00e7\u00f5es Subversivas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html","og_locale":"pt_BR","og_type":"article","og_title":"Cart\u00e3o Ore e Envie... Igrejas ECO Cidad\u00e3s! - Crentassos Produ\u00e7\u00f5es Subversivas","og_description":"O que \u00e9? Cart\u00e3o Ore e Envie \u00e9 uma ferramenta de informa\u00e7\u00e3o, reflex\u00e3o, ora\u00e7\u00e3o e a\u00e7\u00e3o da peti\u00e7\u00e3o\u00a0\u201cFALE por um mundo justo [&hellip;]","og_url":"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html","og_site_name":"Crentassos Produ\u00e7\u00f5es Subversivas","article_publisher":"http:\/\/www.facebook.com\/crentassos","article_published_time":"2012-05-29T21:03:09+00:00","og_image":[{"width":3095,"height":1674,"url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/logo-igrejasecocidadas-png2.png","type":"image\/png"}],"author":"Cristiano Machado","twitter_card":"summary_large_image","twitter_creator":"@crentassos","twitter_site":"@crentassos","twitter_misc":{"Escrito por":"Cristiano Machado","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html#article","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html"},"author":{"name":"Cristiano Machado","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/7ec3329a98c44e20ccd6cc2c9e18acbd"},"headline":"Cart\u00e3o Ore e Envie&#8230; Igrejas ECO Cidad\u00e3s!","datePublished":"2012-05-29T21:03:09+00:00","mainEntityOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html"},"wordCount":162,"commentCount":1,"publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/logo-igrejasecocidadas-png2.png","articleSection":["Artigos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html","url":"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html","name":"Cart\u00e3o Ore e Envie... Igrejas ECO Cidad\u00e3s! - Crentassos Produ\u00e7\u00f5es Subversivas","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html#primaryimage"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/logo-igrejasecocidadas-png2.png","datePublished":"2012-05-29T21:03:09+00:00","breadcrumb":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html#primaryimage","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/logo-igrejasecocidadas-png2.png","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/logo-igrejasecocidadas-png2.png","width":"3095","height":"1674"},{"@type":"BreadcrumbList","@id":"https:\/\/crentassos.com.br\/blog\/2012\/05\/cartao-ore-e-envie-igrejas-eco-cidadas.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/crentassos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Cart\u00e3o Ore e Envie&#8230; Igrejas ECO Cidad\u00e3s!"}]},{"@type":"WebSite","@id":"https:\/\/crentassos.com.br\/blog\/#website","url":"https:\/\/crentassos.com.br\/blog\/","name":"Crentassos Produ\u00e7\u00f5es Subversivas","description":"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos","publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crentassos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/crentassos.com.br\/blog\/#organization","name":"Crentassos Produ\u00e7\u00f5es Subversivas","url":"https:\/\/crentassos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","width":300,"height":300,"caption":"Crentassos Produ\u00e7\u00f5es Subversivas"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/crentassos","https:\/\/x.com\/crentassos","https:\/\/www.instagram.com\/crentassos","https:\/\/www.youtube.com\/crentassos"]},{"@type":"Person","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/7ec3329a98c44e20ccd6cc2c9e18acbd","name":"Cristiano Machado","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g","caption":"Cristiano Machado"},"description":"Cristiano Machado \u00e9 o culpado pelo inicio do COLETIVO CRENTASSOS PRODU\u00c7\u00d5ES SUBVERSIVAS e atua como auxiliar de cirurgi\u00e3o barbeiro, tocando o bumbo, jogando malabares, preparando o elixir, costurando amputa\u00e7\u00f5es e demais atividades relacionadas \u00e0 sua ocupa\u00e7\u00e3o. Pensa n\u00e3o vida em forma de pergunta e nunca de resposta, e tem um profundo sentimento de gratid\u00e3o e amor por sua esposa e filha. Religi\u00e3o: Crist\u00e3o Protestante Reformando-se Estado Civil: Inteiramente apaixonado","sameAs":["http:\/\/crentassos.com.br\/blog"],"url":"https:\/\/crentassos.com.br\/blog\/author\/o_cristiano"}]}},"_links":{"self":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/6370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=6370"}],"version-history":[{"count":2,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/6370\/revisions"}],"predecessor-version":[{"id":6373,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/6370\/revisions\/6373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media\/6371"}],"wp:attachment":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=6370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=6370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=6370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}