{"id":4042,"date":"2012-01-20T14:23:00","date_gmt":"2012-01-20T16:23:00","guid":{"rendered":"http:\/\/crentassos.com.br\/blog\/?p=4042"},"modified":"2012-01-20T14:30:47","modified_gmt":"2012-01-20T16:30:47","slug":"comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay","status":"publish","type":"post","link":"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html","title":{"rendered":"Comunicado de Imprensa, para compartilhamento imediato &#8211; The Pirate Bay"},"content":{"rendered":"<p><em>Segue a tradu\u00e7\u00e3o do texto contido em <a href=\"http:\/\/static.thepiratebay.org\/legal\/sopa.txt\">http:\/\/static.thepiratebay.org\/legal\/sopa.txt<\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<dl id=\"attachment_4043\" class=\"wp-caption alignleft\" style=\"width: 285px;\">\n<dt class=\"wp-caption-dt\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4043\" title=\"Pirate Bay\" src=\"http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2012\/01\/piratebay.png\" alt=\"Pirate Bay\" width=\"275\" height=\"295\" \/><\/dt>\n<dd class=\"wp-caption-dd\"><span style=\"font-size: x-small;\">Pirate Bay<\/span><\/dd>\n<\/dl>\n<p><span style=\"font-family: Trebuchet MS,sans-serif; font-size: x-small;\">Internet, 18 de Janeiro de 2012.<br \/>\nComunicado de Imprensa, para compartilhamento imediato.<\/span><\/p>\n<p><span style=\"font-size: small;\"><strong>100 anos atr\u00e1s, Thomas edison conseguiu a patente para um dispositivo que iria &#8220;fazer para os olhos o que o fon\u00f3grafo faz para as orelhas&#8221;.<\/strong> Ele o chamou de Cinetosc\u00f3pio. Ele n\u00e3o foi apenas o primeiro a gravar um v\u00eddeo, ele foi tamb\u00e9m a primeira pessoa a ter os direitos autorais para gravar.<\/span><\/p>\n<p><span style=\"font-size: small;\"><strong>Por causa das patentes de Edison, era financiamente imposs\u00edvel criar filmes na costa leste da Am\u00e9rica do Norte.<\/strong> Os est\u00fadios portanto relocaram-se para a California, e fundaram o que eles chamam hoje de Hollywood. A raz\u00e3o principal era por l\u00e1 n\u00e3o ter patentes.<\/span><br \/>\n<span style=\"font-size: small;\"><strong>N\u00e3o havia direitos autorais propriamente ditos,<\/strong> ent\u00e3o os est\u00fadios podiam copiar est\u00f3rias antigas e fazer filmes deles &#8211; como Fantasia, um dos maiores sucessos da Disney.<\/span><\/p>\n<p><span style=\"font-size: small;\"><strong>Ent\u00e3o, a base de toda essa ind\u00fastria, que hoje est\u00e1 gritando por perder o controle sobre direitos imateriais, \u00e9 que eles burlaram direitos imateriais.<\/strong> Eles copiaram (ou colocando-se na terminologia deles: &#8220;roubaram&#8221;) trabalhos criativos de outras pessoas, sem pagar por isso. Eles fizeram isso para ter um lucro imenso. Hoje, eles est\u00e3o bem sucedidos, e a maioria dos est\u00fadios est\u00e3o na lista das 500 empresas mais ricas do mundo da revista Fortune. E hoje eles det\u00eam os direitos do que outras pessoas criam.<\/span><\/p>\n<p><span style=\"font-family: Trebuchet MS,sans-serif;\"><br \/>\n<span style=\"font-size: small;\"><strong>Se voc\u00ea quer que algo seja lan\u00e7ado, voc\u00ea tem que concordar com as regras deles.<\/strong> As mesmas que eles criaram depois de burlar regras de outras pessoas.<\/span><\/span><\/p>\n<p><span style=\"font-size: small;\"><strong>Uma raz\u00e3o que eles est\u00e3o sempre reclamando de &#8220;piratas&#8221; hoje em dia \u00e9 simples.<\/strong> N\u00f3s fizemos o que eles fizeram. N\u00f3s burlamos as regras que eles criaram, e criamos as nossas. N\u00f3s quebramos o monop\u00f3lio deles por dar \u00e0s pessoas algo mais eficiente. N\u00f3s permitimos que as pessoas tenham comunica\u00e7\u00e3o direta entre si, burlando o intermedi\u00e1rio lucrador, que em alguns casos recebe 107% dos lucros (sim, voc\u00ea paga para trabalhar para eles).<\/span><\/p>\n<p><span style=\"font-family: Trebuchet MS,sans-serif;\"><br \/>\n<strong><span style=\"font-size: small;\">\u00c9 tudo baseado no fato de que somos competidores.<\/span><\/strong><\/span><\/p>\n<p><span style=\"font-family: Trebuchet MS,sans-serif;\"><br \/>\n<span style=\"font-size: small;\"><strong>N\u00f3s provamos que a exist\u00eancia deles n\u00e3o \u00e9 mais necess\u00e1ria.<\/strong> N\u00f3s somos melhores do que eles.<\/span><\/span><\/p>\n<p><span style=\"font-size: small;\"><strong>E a parte engra\u00e7ada \u00e9 que nossas regras s\u00e3o bem similares com as ideias fundadoras dos EUA.<\/strong> N\u00f3s lutamos por liberdade de express\u00e3o. N\u00f3s vemos todas as pessoas igualmente. N\u00f3s acreditamos que esse p\u00fablico, n\u00e3o a elite, devem governar a na\u00e7\u00e3o. N\u00f3s acreditamos que leis devem ser criadas para servir ao p\u00fablico, n\u00e3o \u00e0s ricas corpora\u00e7\u00f5es.<\/span><\/p>\n<p><span style=\"font-size: small;\"><strong>O Pirate Bay \u00e9 verdadeiramente uma comunidade internacional.<\/strong> A equipe \u00e9 dividida por todo o mundo &#8211; mas n\u00f3s nos mantemos fora dos EUA. N\u00f3s temos raizes suecas e um amigo sueco disse isso:<\/span><\/p>\n<p><span style=\"font-family: Trebuchet MS,sans-serif;\"><br \/>\n<span style=\"font-size: small;\"><strong>A palavra SOPA significa &#8220;lixo&#8221; em sueco. A palavra PIPA significa &#8220;cano&#8221; em sueco.<\/strong> Isso, \u00e9 claro, n\u00e3o \u00e9 uma coincid\u00eancia.<\/span><br \/>\n<span style=\"font-size: small;\">Eles querem transformar a internet em um cano de fluxo \u00fanico, com eles no topo, jogando lixo pelo cano para o resto dos consumidores obedientes.<\/span><\/span><\/p>\n<p><span style=\"font-family: Trebuchet MS,sans-serif;\"><br \/>\n<span style=\"font-size: small;\"><strong>A opini\u00e3o p\u00fablica nesse assunto \u00e9 clara<\/strong>. Pergunte a qualquer um na rua e voc\u00ea ir\u00e1 aprender que ningu\u00e9m quer ser alimentado com lixo. O porqu\u00ea do governo americano querer que as pessoas americanas sejam alimentadas com lixo vai al\u00eam de nossa imagina\u00e7\u00e3o, mas esperamos que voc\u00ea ir\u00e1 par\u00e1-los, antes que todos se afoguem.<\/span><\/span><\/p>\n<p><span style=\"font-size: small;\"><strong>O SOPA n\u00e3o pode fazer nada para parar o The Pirate Bay.<\/strong> No pior caso, iremos mudar nosso dom\u00ednio atual .org para um das centenas de outros nomes que n\u00f3s j\u00e1 usamos. Em pa\u00edses em que o TPB \u00e9 bloqueado (China e Ar\u00e1bia Saudita v\u00eam \u00e0 mente) eles bloqueiam centenas de dom\u00ednios nossos. E funcionou? N\u00e3o muito.<\/span><\/p>\n<p><span style=\"font-size: small;\"><strong>Para arrumar o &#8220;problema da pirataria&#8221; deve-se ir at\u00e9 a fonte do problema.<\/strong> A ind\u00fastria de entretenimento diz que eles est\u00e3o criando &#8220;cultura&#8221;, mas o que eles realmente fazem s\u00e3o coisas como vender bonecas supervalorizadas e fazer garotas de 11 anos ficarem anor\u00e9xicas. Seja trabalhando nas f\u00e1bricas dessas bonecas por praticamente nenhum sal\u00e1rio ou assistindo filmes e programas da TV que as fazem pensar que est\u00e3o gordas.<\/span><\/p>\n<p><span style=\"font-size: small;\"><strong>No grandioso jogo Civilization de Sid Meiers, voc\u00ea pode construir as Maravilhas do mundo.<\/strong> Uma das mais poderosas \u00e9 Hollywood. Com ela, voc\u00ea controla toda cultura e m\u00eddia do mundo. Rupert Murdoch estava feliz com o MySpace e n\u00e3o tinha problemas com a pirataria at\u00e9 que ele falhou. Agora ele est\u00e1 reclamando que o Google \u00e9 a maior fonte de pirataria do mundo &#8211; por que est\u00e1 com inveja. Ele quer reter seu controle mental sobre as pessoas e, claramente, voc\u00ea consegue uma vis\u00e3o mais honesta das coisas na Wikipedia e Google do que na Fox News.<\/span><\/p>\n<p><span style=\"font-size: small;\"><strong>Alguns fatos (anos, datas) est\u00e3o provavelmente erradas nesse comunicado de imprensa<\/strong>. A raz\u00e3o \u00e9 que n\u00e3o podemos acessar essa informa\u00e7\u00e3o com o apag\u00e3o da Wikipedia. Por causa da press\u00e3o dos nossos competidores perdedores. Sentimos muito por isso.<\/span><\/p>\n<p data-ft=\"{&quot;type&quot;:1}\"><strong>THE PIRATE BAY, (K)2012<\/strong><\/p>\n<p>&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>N\u00e3o falo em nome de cada eeditor, falo apenas por mim, Cristiano Machado, que prego a liberdade completa de informa\u00e7\u00e3o. As grandes corpora\u00e7\u00f5es que controlam tudo que consumimos como CULTURA devem cair.<\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: large;\"><strong>Toda a liberdade \u00e9 amea\u00e7ada quando qualquer liberdade \u00e9 amea\u00e7ada!<\/strong><\/span><\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segue a tradu\u00e7\u00e3o do texto contido em http:\/\/static.thepiratebay.org\/legal\/sopa.txt &nbsp; Pirate Bay Internet, 18 de Janeiro de 2012. Comunicado de Imprensa, para compartilhamento [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":4043,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[112],"tags":[1509,384,744,1508],"class_list":["post-4042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","tag-corporacoes","tag-cultura","tag-liberdade","tag-piratebay","post-with-thumbnail","post-with-thumbnail-large"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunicado de Imprensa, para compartilhamento imediato - The Pirate Bay - Crentassos Produ\u00e7\u00f5es Subversivas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicado de Imprensa, para compartilhamento imediato - The Pirate Bay - Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"og:description\" content=\"Segue a tradu\u00e7\u00e3o do texto contido em http:\/\/static.thepiratebay.org\/legal\/sopa.txt &nbsp; Pirate Bay Internet, 18 de Janeiro de 2012. Comunicado de Imprensa, para compartilhamento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html\" \/>\n<meta property=\"og:site_name\" content=\"Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/crentassos\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-20T16:23:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-01-20T16:30:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2012\/01\/piratebay.png\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"295\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Cristiano Machado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@crentassos\" \/>\n<meta name=\"twitter:site\" content=\"@crentassos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristiano Machado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/01\\\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/01\\\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html\"},\"author\":{\"name\":\"Cristiano Machado\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/7ec3329a98c44e20ccd6cc2c9e18acbd\"},\"headline\":\"Comunicado de Imprensa, para compartilhamento imediato &#8211; The Pirate Bay\",\"datePublished\":\"2012-01-20T16:23:00+00:00\",\"dateModified\":\"2012-01-20T16:30:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/01\\\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html\"},\"wordCount\":930,\"commentCount\":21,\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/01\\\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/piratebay.png\",\"keywords\":[\"corpora\u00e7\u00f5es\",\"cultura\",\"liberdade\",\"piratebay\"],\"articleSection\":[\"Artigos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/01\\\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/01\\\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/01\\\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html\",\"name\":\"Comunicado de Imprensa, para compartilhamento imediato - The Pirate Bay - Crentassos Produ\u00e7\u00f5es Subversivas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/01\\\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/01\\\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/piratebay.png\",\"datePublished\":\"2012-01-20T16:23:00+00:00\",\"dateModified\":\"2012-01-20T16:30:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/01\\\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/01\\\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/01\\\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#primaryimage\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/piratebay.png\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/piratebay.png\",\"width\":\"275\",\"height\":\"295\",\"caption\":\"Pirate Bay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2012\\\/01\\\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicado de Imprensa, para compartilhamento imediato &#8211; The Pirate Bay\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"description\":\"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"width\":300,\"height\":300,\"caption\":\"Crentassos Produ\u00e7\u00f5es Subversivas\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/crentassos\",\"https:\\\/\\\/x.com\\\/crentassos\",\"https:\\\/\\\/www.instagram.com\\\/crentassos\",\"https:\\\/\\\/www.youtube.com\\\/crentassos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/7ec3329a98c44e20ccd6cc2c9e18acbd\",\"name\":\"Cristiano Machado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g\",\"caption\":\"Cristiano Machado\"},\"description\":\"Cristiano Machado \u00e9 o culpado pelo inicio do COLETIVO CRENTASSOS PRODU\u00c7\u00d5ES SUBVERSIVAS e atua como auxiliar de cirurgi\u00e3o barbeiro, tocando o bumbo, jogando malabares, preparando o elixir, costurando amputa\u00e7\u00f5es e demais atividades relacionadas \u00e0 sua ocupa\u00e7\u00e3o. Pensa n\u00e3o vida em forma de pergunta e nunca de resposta, e tem um profundo sentimento de gratid\u00e3o e amor por sua esposa e filha. Religi\u00e3o: Crist\u00e3o Protestante Reformando-se Estado Civil: Inteiramente apaixonado\",\"sameAs\":[\"http:\\\/\\\/crentassos.com.br\\\/blog\"],\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/author\\\/o_cristiano\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicado de Imprensa, para compartilhamento imediato - The Pirate Bay - Crentassos Produ\u00e7\u00f5es Subversivas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html","og_locale":"pt_BR","og_type":"article","og_title":"Comunicado de Imprensa, para compartilhamento imediato - The Pirate Bay - Crentassos Produ\u00e7\u00f5es Subversivas","og_description":"Segue a tradu\u00e7\u00e3o do texto contido em http:\/\/static.thepiratebay.org\/legal\/sopa.txt &nbsp; Pirate Bay Internet, 18 de Janeiro de 2012. Comunicado de Imprensa, para compartilhamento [&hellip;]","og_url":"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html","og_site_name":"Crentassos Produ\u00e7\u00f5es Subversivas","article_publisher":"http:\/\/www.facebook.com\/crentassos","article_published_time":"2012-01-20T16:23:00+00:00","article_modified_time":"2012-01-20T16:30:47+00:00","og_image":[{"width":275,"height":295,"url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2012\/01\/piratebay.png","type":"image\/png"}],"author":"Cristiano Machado","twitter_card":"summary_large_image","twitter_creator":"@crentassos","twitter_site":"@crentassos","twitter_misc":{"Escrito por":"Cristiano Machado","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#article","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html"},"author":{"name":"Cristiano Machado","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/7ec3329a98c44e20ccd6cc2c9e18acbd"},"headline":"Comunicado de Imprensa, para compartilhamento imediato &#8211; The Pirate Bay","datePublished":"2012-01-20T16:23:00+00:00","dateModified":"2012-01-20T16:30:47+00:00","mainEntityOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html"},"wordCount":930,"commentCount":21,"publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2012\/01\/piratebay.png","keywords":["corpora\u00e7\u00f5es","cultura","liberdade","piratebay"],"articleSection":["Artigos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html","url":"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html","name":"Comunicado de Imprensa, para compartilhamento imediato - The Pirate Bay - Crentassos Produ\u00e7\u00f5es Subversivas","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#primaryimage"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2012\/01\/piratebay.png","datePublished":"2012-01-20T16:23:00+00:00","dateModified":"2012-01-20T16:30:47+00:00","breadcrumb":{"@id":"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#primaryimage","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2012\/01\/piratebay.png","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2012\/01\/piratebay.png","width":"275","height":"295","caption":"Pirate Bay"},{"@type":"BreadcrumbList","@id":"https:\/\/crentassos.com.br\/blog\/2012\/01\/comunicado-de-imprensa-para-compartilhamento-imediato-the-pirate-bay.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/crentassos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Comunicado de Imprensa, para compartilhamento imediato &#8211; The Pirate Bay"}]},{"@type":"WebSite","@id":"https:\/\/crentassos.com.br\/blog\/#website","url":"https:\/\/crentassos.com.br\/blog\/","name":"Crentassos Produ\u00e7\u00f5es Subversivas","description":"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos","publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crentassos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/crentassos.com.br\/blog\/#organization","name":"Crentassos Produ\u00e7\u00f5es Subversivas","url":"https:\/\/crentassos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","width":300,"height":300,"caption":"Crentassos Produ\u00e7\u00f5es Subversivas"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/crentassos","https:\/\/x.com\/crentassos","https:\/\/www.instagram.com\/crentassos","https:\/\/www.youtube.com\/crentassos"]},{"@type":"Person","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/7ec3329a98c44e20ccd6cc2c9e18acbd","name":"Cristiano Machado","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g","caption":"Cristiano Machado"},"description":"Cristiano Machado \u00e9 o culpado pelo inicio do COLETIVO CRENTASSOS PRODU\u00c7\u00d5ES SUBVERSIVAS e atua como auxiliar de cirurgi\u00e3o barbeiro, tocando o bumbo, jogando malabares, preparando o elixir, costurando amputa\u00e7\u00f5es e demais atividades relacionadas \u00e0 sua ocupa\u00e7\u00e3o. Pensa n\u00e3o vida em forma de pergunta e nunca de resposta, e tem um profundo sentimento de gratid\u00e3o e amor por sua esposa e filha. Religi\u00e3o: Crist\u00e3o Protestante Reformando-se Estado Civil: Inteiramente apaixonado","sameAs":["http:\/\/crentassos.com.br\/blog"],"url":"https:\/\/crentassos.com.br\/blog\/author\/o_cristiano"}]}},"_links":{"self":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/4042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4042"}],"version-history":[{"count":4,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/4042\/revisions"}],"predecessor-version":[{"id":4046,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/4042\/revisions\/4046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media\/4043"}],"wp:attachment":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}