{"id":1620,"date":"2010-03-11T01:58:00","date_gmt":"2010-03-11T03:58:00","guid":{"rendered":"http:\/\/oueleouela.wordpress.com\/2010\/03\/11\/o-elvis-brasileiro"},"modified":"2010-03-11T01:58:00","modified_gmt":"2010-03-11T03:58:00","slug":"o-elvis-brasileiro","status":"publish","type":"post","link":"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html","title":{"rendered":"O Elvis Brasileiro&#8230;"},"content":{"rendered":"<div class=\"separator\" style=\"clear:both;font-family:Verdana,sans-serif;text-align:center;\"><a href=\"http:\/\/lh6.ggpht.com\/_-G6-mRrkxDM\/S5hpJ6YOHcI\/AAAAAAAAMNQ\/TnLWKBVLQ9Q\/s1600\/martinho-299x300.png\" style=\"clear:left;float:left;margin-bottom:1em;margin-right:1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"200\" src=\"http:\/\/lh6.ggpht.com\/_-G6-mRrkxDM\/S5hpJ6YOHcI\/AAAAAAAAMNQ\/TnLWKBVLQ9Q\/s200\/martinho-299x300.png\" width=\"198\" \/><\/a><\/div>\n<div style=\"font-family:Verdana,sans-serif;text-align:justify;\"><i>Segue uma parada muito curiosa&#8230; sempre achei q o pai do &#8220;gospel&#8221; (cuspa&#8230;) teria sido o Brother Simion, entretanto achei um cara mais antigo e q parece ser a mais antiga referencia de musica Crist\u00e3 evangel\u00edstica&#8230; segue o texto.<\/i><\/div>\n<div style=\"font-family:Verdana,sans-serif;text-align:justify;\"><\/div>\n<div style=\"font-family:Verdana,sans-serif;text-align:justify;\">Muita gente n\u00e3o sabe, mais foi o cantor country brasileiro Martin Lutero quem introduziu o termo \u201cgospel\u201d no Brasil, l\u00e1 pelos meados dos anos 80. Nascido em Recife-PE e criado na igreja desde a inf\u00e2ncia por seus pais, ele foi ensinado a cantar e tocar na congrega\u00e7\u00e3o, tendo convivido bastante, tamb\u00e9m, com mission\u00e1rios norte-americanos, de quem recebeu influ\u00eancia espiritual e musical e, tamb\u00e9m, aprendeu a l\u00edngua inglesa.<\/div>\n<div style=\"font-family:Verdana,sans-serif;text-align:justify;\">Com um vocal privilegiado, parecid\u00edssimo com a voz de Elvis Presley. Agora anda compartilhando o seu dom e talento entre os norte-americanos.<\/div>\n<div style=\"font-family:Verdana,sans-serif;text-align:justify;\">Al\u00e9m de int\u00e9rprete, instrumentista e compositor, Martin Lutero fez diversas vers\u00f5es de c\u00e2nticos antigos, inclusive de can\u00e7\u00f5es gospel interpretadas pelo pr\u00f3prio Elvis Presley.<br \/>Atualmente Martin Lutero \u00e9 pastor da First Mighty Fortress Baptist Church,\u00a0(Primeira Igreja Batista Castelo Forte) da Conven\u00e7\u00e3o do Sul \u2013 USA,\u00a0na cidade de Mendon, em Massachusetts, Estados Unidos, onde reside desde 1998, com o filho Glenn Martin de 7 anos e com sua esposa Doni, com quem \u00e9 casado h\u00e1 20 anos.<\/div>\n<div style=\"font-family:Verdana,sans-serif;\">No Brasil lan\u00e7ou 5 discos em vinil: os LPs Ponte Sobre \u00c1guas Turvas (1984), Energia (1986), Esta\u00e7\u00f5es (Country Gospel) (1987), Estradas (1990) e Chuva Fina (1993). Em 1997 foi lan\u00e7ada uma colet\u00e2nea de 2 CDs, contendo suas 26 melhores can\u00e7\u00f5es. Nos Estados Unidos lan\u00e7ou, em ingl\u00eas, os CDs How Great Thou Art (1998) e Christmas Serenade (2001) e, tamb\u00e9m, o CD Si non fuera el Senor, em Espanhol.<\/div>\n<div style=\"font-family:Verdana,sans-serif;\"><\/div>\n<div style=\"font-family:Verdana,sans-serif;\"><\/div>\n<div style=\"font-family:Verdana,sans-serif;\">link para baixar o cd Ponte Sobre \u00c1guas Turvas (1984):<br \/><a href=\"http:\/\/www.mediafire.com\/?yynmazemdhx\" target=\"_blank\">http:\/\/www.mediafire.com\/?yynmazemdhx<\/a><\/p>\n<p>Cr\u00e9ditos: Roberto Britto<\/p><\/div>\n<div style=\"font-family:Verdana,sans-serif;\">dica do meu querido <a href=\"http:\/\/twitter.com\/samoia\">Samoia<\/a><br \/>\u00a0&#8212;- <br \/>Cristiano Machado diz:<br \/>Ainda assim acho q o termo &#8220;G\u00f3spel&#8221; terrivelmente comercial&#8230; e apenas comercial<br \/>\u00a0<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Segue uma parada muito curiosa&#8230; sempre achei q o pai do &#8220;gospel&#8221; (cuspa&#8230;) teria sido o Brother Simion, entretanto achei um cara [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[],"tags":[387,451,778,1251],"class_list":["post-1620","post","type-post","status-publish","format-standard","hentry","tag-curiosidades","tag-download","tag-martin-lutero","tag-musica-boa-18"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O Elvis Brasileiro... - Crentassos Produ\u00e7\u00f5es Subversivas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O Elvis Brasileiro... - Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"og:description\" content=\"Segue uma parada muito curiosa&#8230; sempre achei q o pai do &#8220;gospel&#8221; (cuspa&#8230;) teria sido o Brother Simion, entretanto achei um cara [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html\" \/>\n<meta property=\"og:site_name\" content=\"Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/crentassos\" \/>\n<meta property=\"article:published_time\" content=\"2010-03-11T03:58:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/lh6.ggpht.com\/_-G6-mRrkxDM\/S5hpJ6YOHcI\/AAAAAAAAMNQ\/TnLWKBVLQ9Q\/s200\/martinho-299x300.png\" \/>\n<meta name=\"author\" content=\"Crentassos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@crentassos\" \/>\n<meta name=\"twitter:site\" content=\"@crentassos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Crentassos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2010\\\/03\\\/o-elvis-brasileiro.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2010\\\/03\\\/o-elvis-brasileiro.html\"},\"author\":{\"name\":\"Crentassos\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/c143e75f920e3ad15d83540f47db500c\"},\"headline\":\"O Elvis Brasileiro&#8230;\",\"datePublished\":\"2010-03-11T03:58:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2010\\\/03\\\/o-elvis-brasileiro.html\"},\"wordCount\":323,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2010\\\/03\\\/o-elvis-brasileiro.html#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/lh6.ggpht.com\\\/_-G6-mRrkxDM\\\/S5hpJ6YOHcI\\\/AAAAAAAAMNQ\\\/TnLWKBVLQ9Q\\\/s200\\\/martinho-299x300.png\",\"keywords\":[\"curiosidades\",\"download\",\"martin lutero\",\"m\u00fasica boa\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2010\\\/03\\\/o-elvis-brasileiro.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2010\\\/03\\\/o-elvis-brasileiro.html\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2010\\\/03\\\/o-elvis-brasileiro.html\",\"name\":\"O Elvis Brasileiro... - Crentassos Produ\u00e7\u00f5es Subversivas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2010\\\/03\\\/o-elvis-brasileiro.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2010\\\/03\\\/o-elvis-brasileiro.html#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/lh6.ggpht.com\\\/_-G6-mRrkxDM\\\/S5hpJ6YOHcI\\\/AAAAAAAAMNQ\\\/TnLWKBVLQ9Q\\\/s200\\\/martinho-299x300.png\",\"datePublished\":\"2010-03-11T03:58:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2010\\\/03\\\/o-elvis-brasileiro.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2010\\\/03\\\/o-elvis-brasileiro.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2010\\\/03\\\/o-elvis-brasileiro.html#primaryimage\",\"url\":\"http:\\\/\\\/lh6.ggpht.com\\\/_-G6-mRrkxDM\\\/S5hpJ6YOHcI\\\/AAAAAAAAMNQ\\\/TnLWKBVLQ9Q\\\/s200\\\/martinho-299x300.png\",\"contentUrl\":\"http:\\\/\\\/lh6.ggpht.com\\\/_-G6-mRrkxDM\\\/S5hpJ6YOHcI\\\/AAAAAAAAMNQ\\\/TnLWKBVLQ9Q\\\/s200\\\/martinho-299x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2010\\\/03\\\/o-elvis-brasileiro.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O Elvis Brasileiro&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"description\":\"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"width\":300,\"height\":300,\"caption\":\"Crentassos Produ\u00e7\u00f5es Subversivas\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/crentassos\",\"https:\\\/\\\/x.com\\\/crentassos\",\"https:\\\/\\\/www.instagram.com\\\/crentassos\",\"https:\\\/\\\/www.youtube.com\\\/crentassos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/c143e75f920e3ad15d83540f47db500c\",\"name\":\"Crentassos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb1b9c88bcd90ec2f909823639a352ece8d3a3cea59b9d08637fe057502fa227?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb1b9c88bcd90ec2f909823639a352ece8d3a3cea59b9d08637fe057502fa227?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb1b9c88bcd90ec2f909823639a352ece8d3a3cea59b9d08637fe057502fa227?s=96&d=retro&r=g\",\"caption\":\"Crentassos\"},\"description\":\"Perfil padr\u00e3o do blog dos Crentassos.\",\"sameAs\":[\"http:\\\/\\\/www.crentassos.com.br\"],\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/author\\\/crentassos\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Elvis Brasileiro... - Crentassos Produ\u00e7\u00f5es Subversivas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html","og_locale":"pt_BR","og_type":"article","og_title":"O Elvis Brasileiro... - Crentassos Produ\u00e7\u00f5es Subversivas","og_description":"Segue uma parada muito curiosa&#8230; sempre achei q o pai do &#8220;gospel&#8221; (cuspa&#8230;) teria sido o Brother Simion, entretanto achei um cara [&hellip;]","og_url":"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html","og_site_name":"Crentassos Produ\u00e7\u00f5es Subversivas","article_publisher":"http:\/\/www.facebook.com\/crentassos","article_published_time":"2010-03-11T03:58:00+00:00","og_image":[{"url":"http:\/\/lh6.ggpht.com\/_-G6-mRrkxDM\/S5hpJ6YOHcI\/AAAAAAAAMNQ\/TnLWKBVLQ9Q\/s200\/martinho-299x300.png","type":"","width":"","height":""}],"author":"Crentassos","twitter_card":"summary_large_image","twitter_creator":"@crentassos","twitter_site":"@crentassos","twitter_misc":{"Escrito por":"Crentassos","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html#article","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html"},"author":{"name":"Crentassos","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/c143e75f920e3ad15d83540f47db500c"},"headline":"O Elvis Brasileiro&#8230;","datePublished":"2010-03-11T03:58:00+00:00","mainEntityOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html"},"wordCount":323,"commentCount":4,"publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html#primaryimage"},"thumbnailUrl":"http:\/\/lh6.ggpht.com\/_-G6-mRrkxDM\/S5hpJ6YOHcI\/AAAAAAAAMNQ\/TnLWKBVLQ9Q\/s200\/martinho-299x300.png","keywords":["curiosidades","download","martin lutero","m\u00fasica boa"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html","url":"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html","name":"O Elvis Brasileiro... - Crentassos Produ\u00e7\u00f5es Subversivas","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html#primaryimage"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html#primaryimage"},"thumbnailUrl":"http:\/\/lh6.ggpht.com\/_-G6-mRrkxDM\/S5hpJ6YOHcI\/AAAAAAAAMNQ\/TnLWKBVLQ9Q\/s200\/martinho-299x300.png","datePublished":"2010-03-11T03:58:00+00:00","breadcrumb":{"@id":"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html#primaryimage","url":"http:\/\/lh6.ggpht.com\/_-G6-mRrkxDM\/S5hpJ6YOHcI\/AAAAAAAAMNQ\/TnLWKBVLQ9Q\/s200\/martinho-299x300.png","contentUrl":"http:\/\/lh6.ggpht.com\/_-G6-mRrkxDM\/S5hpJ6YOHcI\/AAAAAAAAMNQ\/TnLWKBVLQ9Q\/s200\/martinho-299x300.png"},{"@type":"BreadcrumbList","@id":"https:\/\/crentassos.com.br\/blog\/2010\/03\/o-elvis-brasileiro.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/crentassos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"O Elvis Brasileiro&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/crentassos.com.br\/blog\/#website","url":"https:\/\/crentassos.com.br\/blog\/","name":"Crentassos Produ\u00e7\u00f5es Subversivas","description":"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos","publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crentassos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/crentassos.com.br\/blog\/#organization","name":"Crentassos Produ\u00e7\u00f5es Subversivas","url":"https:\/\/crentassos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","width":300,"height":300,"caption":"Crentassos Produ\u00e7\u00f5es Subversivas"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/crentassos","https:\/\/x.com\/crentassos","https:\/\/www.instagram.com\/crentassos","https:\/\/www.youtube.com\/crentassos"]},{"@type":"Person","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/c143e75f920e3ad15d83540f47db500c","name":"Crentassos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/cb1b9c88bcd90ec2f909823639a352ece8d3a3cea59b9d08637fe057502fa227?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cb1b9c88bcd90ec2f909823639a352ece8d3a3cea59b9d08637fe057502fa227?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb1b9c88bcd90ec2f909823639a352ece8d3a3cea59b9d08637fe057502fa227?s=96&d=retro&r=g","caption":"Crentassos"},"description":"Perfil padr\u00e3o do blog dos Crentassos.","sameAs":["http:\/\/www.crentassos.com.br"],"url":"https:\/\/crentassos.com.br\/blog\/author\/crentassos"}]}},"_links":{"self":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1620"}],"version-history":[{"count":1,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1620\/revisions"}],"predecessor-version":[{"id":13424,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1620\/revisions\/13424"}],"wp:attachment":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}