{"id":13680,"date":"2017-10-01T09:37:40","date_gmt":"2017-10-01T12:37:40","guid":{"rendered":"http:\/\/crentassos.com.br\/blog\/?p=13680"},"modified":"2023-06-03T17:10:59","modified_gmt":"2023-06-03T19:10:59","slug":"da-prateleira-05-o-morro-dos-ventos-uivantes","status":"publish","type":"post","link":"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html","title":{"rendered":"O Morro dos Ventos Uivantes | Da Prateleira 05"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"4418\" height=\"2492\" src=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/09\/05-O-Morro-Dos-Ventos-Uivantes.jpg\" alt=\"\" class=\"wp-image-13681\" srcset=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/09\/05-O-Morro-Dos-Ventos-Uivantes.jpg 4418w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/09\/05-O-Morro-Dos-Ventos-Uivantes-275x154.jpg 275w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/09\/05-O-Morro-Dos-Ventos-Uivantes-300x169.jpg 300w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/09\/05-O-Morro-Dos-Ventos-Uivantes-768x433.jpg 768w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/09\/05-O-Morro-Dos-Ventos-Uivantes-620x350.jpg 620w\" sizes=\"auto, (max-width: 4418px) 100vw, 4418px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/open.spotify.com\/episode\/0LpJS4Guz4cqvfg8EnoyVT\n<\/div><\/figure>\n\n\n<p style=\"text-align: justify;\">O\u00a0<a href=\"http:\/\/crentassos.com.br\/blog\/category\/podcasts\/da-prateleira\"><em>Da Prateleira<\/em><\/a>\u00a0ser\u00e1\u00a0um\u00a0programa onde eu,\u00a0<a href=\"https:\/\/twitter.com\/tamyrespalma\">Tamyres<\/a>, indicarei livros, quadrinhos, filmes, s\u00e9ries ou \u00e1lbuns que me agradem. Eventualmente com convidados, \u00e0s vezes sozinha, estarei aqui indicando obras e convidando voc\u00eas a discorrerem sobre suas impress\u00f5es nos coment\u00e1rios.<\/p>\n<p style=\"text-align: justify;\">Como o programa \u00e9 para indicar obras, n\u00e3o ser\u00e3o dados spoilers sobre a mesma em quest\u00e3o, para que aqueles que ainda n\u00e3o a conhecem possam ouvir o programa tranquilamente.<\/p>\n<p style=\"text-align: justify;\">No\u00a0quinto epis\u00f3dio\u00a0do\u00a0<a href=\"http:\/\/crentassos.com.br\/blog\/tag\/da-prateleira\"><em>Da Prateleira<\/em><\/a>, converso com a Eva sobre esse cl\u00e1ssico da literatura inglesa, que vem incomodando a sociedade desde sua publica\u00e7\u00e3o, em virtude de seus personagens controversos.<\/p>\n<p style=\"text-align: justify;\"><strong>PARTICIPANTES:<\/strong><br \/>&#8211;\u00a0<a href=\"https:\/\/twitter.com\/tamyrespalma\">Tamyres Palma<br \/><\/a>&#8211; Eva Holland<a href=\"https:\/\/twitter.com\/tamyrespalma\"><br \/><\/a><br \/><strong>COISAS \u00daTEIS:<\/strong><br \/>&#8211; Dura\u00e7\u00e3o: 46<em>m04s<\/em><br \/>&#8211; Feed do Crentassos:\u00a0<em>Feed, RSS, Android e iTunes:\u00a0<a href=\"https:\/\/crentassos.com.br\/blog\/feed\/podcast\">crentassos.com.br\/blog\/<wbr \/>tag\/podcast\/feed<\/a>\u00a0Para assinar no iTunes, clique na aba Avan\u00e7ado, e Assinar Podcast. Cole o endere\u00e7o e confirme. Assim voc\u00ea recebe automaticamente os novos epis\u00f3dios.<\/em><\/p>\n<p><strong>CITADOS NO PROGRAMA:<br \/><\/strong>&#8211; <a href=\"https:\/\/www.amazon.com.br\/Morro-Ventos-Uivantes-Cl%C3%A1ssicos-Zahar\/dp\/8537815756?tag=goog0ef-20&amp;smid=A1ZZFT5FULY4LN&amp;ascsubtag=4cebbf38-9a5c-45a1-960b-e813534637e2\">&#8220;O Morro dos Ventos Uivantes&#8221; na Amazon;<\/a><strong><br \/><\/strong>&#8211; <a href=\"https:\/\/en.wikipedia.org\/wiki\/Poems_by_Currer,_Ellis,_and_Acton_Bell\">Livro de poemas das irm\u00e3s Bront\u00eb;<\/a><br \/>&#8211; <a href=\"http:\/\/www.zahar.com.br\/livro\/o-morro-dos-ventos-uivantes-edicao-comentada\">&#8220;O Morro dos Ventos Uivantes&#8221;, vers\u00e3o que foi usada na vitrine do programa;<\/a><br \/>&#8211; <a href=\"http:\/\/www.lpm.com.br\/site\/imprimir.asp?Template=..\/livros\/layout_produto.asp&amp;CategoriaID=636453&amp;ID=946300\">&#8220;O Morro dos Ventos Uivantes&#8221;, vers\u00e3o que a Tamyres tem.<\/a><\/p>\n<p><strong>TRILHA SONORA DO PROGRAMA:<\/strong><br \/>&#8211;\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=ZcoNxmU8Ecw\" target=\"_blank\" rel=\"noopener noreferrer\">&#8220;Postcards From Italy&#8221; &#8211; Beirut (Ukelele Instrumental por iamblinkin)<\/a><\/p>\n<p><strong>OU\u00c7A O\u00a0PROGRAMA PELO YOUTUBE:<br \/><\/strong>&#8211;\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=ZUOn0TvXjcQ\">Da Prateleira 05 |\u00a0O\u00a0Morro dos Ventos Uivantes<\/a><\/p>\n<p><strong>JAB\u00c1S:<\/strong><a href=\"https:\/\/www.padrim.com.br\/crentassos\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/04\/Padrim-Banner.jpg\" alt=\"Padrim Banner\" width=\"4418\" height=\"500\" \/><\/a><a href=\"https:\/\/bit.ly\/picpaycrentassos\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-15115 size-full\" src=\"http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2018\/08\/picpay-2.jpg\" alt=\"picpay\" width=\"4418\" height=\"500\" srcset=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2018\/08\/picpay-2.jpg 4418w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2018\/08\/picpay-2-300x34.jpg 300w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2018\/08\/picpay-2-768x87.jpg 768w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2018\/08\/picpay-2-620x70.jpg 620w\" sizes=\"auto, (max-width: 4418px) 100vw, 4418px\" \/><\/a><br \/><a href=\"https:\/\/umapenca.com\/crentassos\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18569 size-full\" src=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/08\/Banners-Loja.jpg\" alt=\"\" width=\"2560\" height=\"290\" srcset=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/08\/Banners-Loja.jpg 2560w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/08\/Banners-Loja-300x34.jpg 300w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/08\/Banners-Loja-620x70.jpg 620w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/08\/Banners-Loja-768x87.jpg 768w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/08\/Banners-Loja-1536x174.jpg 1536w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/08\/Banners-Loja-2048x232.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/amzn.to\/2CcHPhC\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13992 size-full\" src=\"http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2018\/02\/Amazon-Banner.jpg\" alt=\"Amazon Banner\" width=\"4418\" height=\"500\" srcset=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2018\/02\/Amazon-Banner.jpg 4418w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2018\/02\/Amazon-Banner-300x34.jpg 300w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2018\/02\/Amazon-Banner-768x87.jpg 768w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2018\/02\/Amazon-Banner-620x70.jpg 620w\" sizes=\"auto, (max-width: 4418px) 100vw, 4418px\" \/><\/a><\/p>\n<p><strong>REDES SOCIAIS:<\/strong><br \/><a href=\"https:\/\/www.facebook.com\/Crentassos\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13593 size-medium\" src=\"http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Facebook-Post-300x34.jpg\" alt=\"Facebook Post\" width=\"300\" height=\"34\" srcset=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Facebook-Post-300x34.jpg 300w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Facebook-Post-768x87.jpg 768w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Facebook-Post-620x70.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/twitter.com\/crentassos\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13595 size-medium\" src=\"http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Twitter-Post-300x34.jpg\" alt=\"Twitter Post\" width=\"300\" height=\"34\" srcset=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Twitter-Post-300x34.jpg 300w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Twitter-Post-768x87.jpg 768w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Twitter-Post-620x70.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/www.instagram.com\/crentassos\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13594 size-medium\" src=\"http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Instagram-Post-300x34.jpg\" alt=\"Instagram Post\" width=\"300\" height=\"34\" srcset=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Instagram-Post-300x34.jpg 300w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Instagram-Post-768x87.jpg 768w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Instagram-Post-620x70.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/www.youtube.com\/user\/Crentassos\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13596 size-medium\" src=\"http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Youtube-Post-300x34.jpg\" alt=\"Youtube Post\" width=\"300\" height=\"34\" srcset=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Youtube-Post-300x34.jpg 300w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Youtube-Post-768x87.jpg 768w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Youtube-Post-620x70.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"mailto:crentassos@gmail.com\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13592 size-medium\" src=\"http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Email-Post-300x34.jpg\" alt=\"Email Post\" width=\"300\" height=\"34\" srcset=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Email-Post-300x34.jpg 300w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Email-Post-768x87.jpg 768w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/08\/Email-Post-620x70.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><strong><em>Cr\u00edticas, coment\u00e1rios, sugest\u00f5es para\u00a0<a href=\"mailto:crentassos@gmail.com\">crentassos@gmail.com<\/a>\u00a0ou nos coment\u00e1rios desse post.<\/em><\/strong><\/p>\n<p><strong>OU\u00c7A\/BAIXE O PROGRAMA:<\/strong><\/p><div class=\"powerpress_player\" id=\"powerpress_player_9514\"><audio class=\"wp-audio-shortcode\" id=\"audio-13680-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/media.blubrry.com\/podcrent\/media.blubrry.com\/podcrent_crentassos_blog\/www.crentassos.com.br\/podcrent\/daprateleira\/daprateleira005.mp3?_=1\" \/><a href=\"http:\/\/media.blubrry.com\/podcrent\/media.blubrry.com\/podcrent_crentassos_blog\/www.crentassos.com.br\/podcrent\/daprateleira\/daprateleira005.mp3\">http:\/\/media.blubrry.com\/podcrent\/media.blubrry.com\/podcrent_crentassos_blog\/www.crentassos.com.br\/podcrent\/daprateleira\/daprateleira005.mp3<\/a><\/audio><\/div><p class=\"powerpress_links powerpress_links_mp3\" style=\"margin-bottom: 1px !important;\">Podcast: <a href=\"http:\/\/media.blubrry.com\/podcrent\/media.blubrry.com\/podcrent_crentassos_blog\/www.crentassos.com.br\/podcrent\/daprateleira\/daprateleira005.mp3\" class=\"powerpress_link_pinw\" target=\"_blank\" title=\"Play in new window\" onclick=\"return powerpress_pinw('https:\/\/crentassos.com.br\/blog\/?powerpress_pinw=13680-podcast');\" rel=\"nofollow\">Play in new window<\/a> | <a href=\"http:\/\/media.blubrry.com\/podcrent\/media.blubrry.com\/podcrent_crentassos_blog\/www.crentassos.com.br\/podcrent\/daprateleira\/daprateleira005.mp3\" class=\"powerpress_link_d\" title=\"Download\" rel=\"nofollow\" download=\"daprateleira005.mp3\">Download<\/a> (Duration: 46:05 &#8212; 32.4MB) | <a href=\"#\" class=\"powerpress_link_e\" title=\"Embed\" onclick=\"return powerpress_show_embed('13680-podcast');\" rel=\"nofollow\">Embed<\/a><\/p><p class=\"powerpress_embed_box\" id=\"powerpress_embed_13680-podcast\" style=\"display: none;\"><input id=\"powerpress_embed_13680-podcast_t\" type=\"text\" value=\"&lt;iframe width=&quot;320&quot; height=&quot;30&quot; src=&quot;https:\/\/crentassos.com.br\/blog\/?powerpress_embed=13680-podcast&amp;amp;powerpress_player=mediaelement-audio&quot; title=&quot;Blubrry Podcast Player&quot; frameborder=&quot;0&quot; scrolling=&quot;no&quot;&gt;&lt;\/iframe&gt;\" onclick=\"javascript: this.select();\" onfocus=\"javascript: this.select();\" style=\"width: 70%;\" readOnly><\/p><p class=\"powerpress_links powerpress_subscribe_links\">Assine! <a href=\"https:\/\/open.spotify.com\/show\/2WZAzWymTxxdr0DNi0R6pB\" class=\"powerpress_link_subscribe powerpress_link_subscribe_spotify\" target=\"_blank\" title=\"Subscribe on Spotify\" rel=\"nofollow\">Spotify<\/a> | <a href=\"https:\/\/www.deezer.com\/us\/show\/511482\" class=\"powerpress_link_subscribe powerpress_link_subscribe_deezer\" target=\"_blank\" title=\"Subscribe on Deezer\" rel=\"nofollow\">Deezer<\/a> | <a href=\"https:\/\/crentassos.com.br\/blog\/feed\/podcast\" class=\"powerpress_link_subscribe powerpress_link_subscribe_rss\" target=\"_blank\" title=\"Subscribe via RSS\" rel=\"nofollow\">RSS<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>O\u00a0Da Prateleira\u00a0ser\u00e1\u00a0um\u00a0programa onde eu,\u00a0Tamyres, indicarei livros, quadrinhos, filmes, s\u00e9ries ou \u00e1lbuns que me agradem. Eventualmente com convidados, \u00e0s vezes sozinha, estarei aqui [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":13681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[6486,6489,5942,6010,1304],"tags":[370,6490,6631,6628,6492,747,1870,6630,43,6500,1868,6491,6102,2819],"class_list":["post-13680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-da-prateleira","category-indicacao","category-livro","category-livros","category-podcasts","tag-crentassos","tag-da-prateleira","tag-emily-bronte-emily-bronte","tag-eva-holland","tag-indicacao","tag-literatura","tag-livro","tag-o-morro-dos-ventos-uivantes","tag-podcast","tag-podcast-de-livro","tag-podcasts-2","tag-prateleira","tag-tamyres-palma","tag-video-destaque","post-with-thumbnail","post-with-thumbnail-large"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O Morro dos Ventos Uivantes | Da Prateleira 05 - Crentassos Produ\u00e7\u00f5es Subversivas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O Morro dos Ventos Uivantes | Da Prateleira 05 - Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"og:description\" content=\"O\u00a0Da Prateleira\u00a0ser\u00e1\u00a0um\u00a0programa onde eu,\u00a0Tamyres, indicarei livros, quadrinhos, filmes, s\u00e9ries ou \u00e1lbuns que me agradem. Eventualmente com convidados, \u00e0s vezes sozinha, estarei aqui [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html\" \/>\n<meta property=\"og:site_name\" content=\"Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/crentassos\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-01T12:37:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-03T19:10:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/09\/05-O-Morro-Dos-Ventos-Uivantes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4418\" \/>\n\t<meta property=\"og:image:height\" content=\"2492\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tamyres Palma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@crentassos\" \/>\n<meta name=\"twitter:site\" content=\"@crentassos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tamyres Palma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2017\\\/10\\\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2017\\\/10\\\/da-prateleira-05-o-morro-dos-ventos-uivantes.html\"},\"author\":{\"name\":\"Tamyres Palma\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/3f5f08a8ba3e2bc991eb2fd8f8e3988c\"},\"headline\":\"O Morro dos Ventos Uivantes | Da Prateleira 05\",\"datePublished\":\"2017-10-01T12:37:40+00:00\",\"dateModified\":\"2023-06-03T19:10:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2017\\\/10\\\/da-prateleira-05-o-morro-dos-ventos-uivantes.html\"},\"wordCount\":279,\"commentCount\":6,\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2017\\\/10\\\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/05-O-Morro-Dos-Ventos-Uivantes.jpg\",\"keywords\":[\"crentassos\",\"da prateleira\",\"emily bronte. emily bront\u00eb\",\"eva holland\",\"indica\u00e7\u00e3o\",\"literatura\",\"livro\",\"o morro dos ventos uivantes\",\"podcast\",\"podcast de livro\",\"podcasts\",\"prateleira\",\"tamyres palma\",\"video-destaque\"],\"articleSection\":[\"Da Prateleira\",\"indica\u00e7\u00e3o\",\"livro\",\"livros\",\"Podcasts\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2017\\\/10\\\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2017\\\/10\\\/da-prateleira-05-o-morro-dos-ventos-uivantes.html\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2017\\\/10\\\/da-prateleira-05-o-morro-dos-ventos-uivantes.html\",\"name\":\"O Morro dos Ventos Uivantes | Da Prateleira 05 - Crentassos Produ\u00e7\u00f5es Subversivas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2017\\\/10\\\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2017\\\/10\\\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/05-O-Morro-Dos-Ventos-Uivantes.jpg\",\"datePublished\":\"2017-10-01T12:37:40+00:00\",\"dateModified\":\"2023-06-03T19:10:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2017\\\/10\\\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2017\\\/10\\\/da-prateleira-05-o-morro-dos-ventos-uivantes.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2017\\\/10\\\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#primaryimage\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/05-O-Morro-Dos-Ventos-Uivantes.jpg\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/05-O-Morro-Dos-Ventos-Uivantes.jpg\",\"width\":4418,\"height\":2492},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2017\\\/10\\\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O Morro dos Ventos Uivantes | Da Prateleira 05\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"description\":\"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"width\":300,\"height\":300,\"caption\":\"Crentassos Produ\u00e7\u00f5es Subversivas\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/crentassos\",\"https:\\\/\\\/x.com\\\/crentassos\",\"https:\\\/\\\/www.instagram.com\\\/crentassos\",\"https:\\\/\\\/www.youtube.com\\\/crentassos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/3f5f08a8ba3e2bc991eb2fd8f8e3988c\",\"name\":\"Tamyres Palma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dce0caea2bafdb6394abc6c84348788083c31d52a278ed4b42bd0ee15c4ed52?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dce0caea2bafdb6394abc6c84348788083c31d52a278ed4b42bd0ee15c4ed52?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dce0caea2bafdb6394abc6c84348788083c31d52a278ed4b42bd0ee15c4ed52?s=96&d=retro&r=g\",\"caption\":\"Tamyres Palma\"},\"description\":\"Tamyres Palma: formada em hist\u00f3ria, apaixonada por livros e casada com o @jonathazimmer . Maluca por Harry Potter, N\u00e1rnia e universos fant\u00e1sticos como a Terra M\u00e9dia. Apaixonada por literatura de forma geral, embora esteja longe do meu ideal de conhecimento liter\u00e1rio.\",\"sameAs\":[\"http:\\\/\\\/cafeecoberta.blogspot.com\"],\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/author\\\/tamyrespalma\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Morro dos Ventos Uivantes | Da Prateleira 05 - Crentassos Produ\u00e7\u00f5es Subversivas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html","og_locale":"pt_BR","og_type":"article","og_title":"O Morro dos Ventos Uivantes | Da Prateleira 05 - Crentassos Produ\u00e7\u00f5es Subversivas","og_description":"O\u00a0Da Prateleira\u00a0ser\u00e1\u00a0um\u00a0programa onde eu,\u00a0Tamyres, indicarei livros, quadrinhos, filmes, s\u00e9ries ou \u00e1lbuns que me agradem. Eventualmente com convidados, \u00e0s vezes sozinha, estarei aqui [&hellip;]","og_url":"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html","og_site_name":"Crentassos Produ\u00e7\u00f5es Subversivas","article_publisher":"http:\/\/www.facebook.com\/crentassos","article_published_time":"2017-10-01T12:37:40+00:00","article_modified_time":"2023-06-03T19:10:59+00:00","og_image":[{"width":4418,"height":2492,"url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/09\/05-O-Morro-Dos-Ventos-Uivantes.jpg","type":"image\/jpeg"}],"author":"Tamyres Palma","twitter_card":"summary_large_image","twitter_creator":"@crentassos","twitter_site":"@crentassos","twitter_misc":{"Escrito por":"Tamyres Palma","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#article","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html"},"author":{"name":"Tamyres Palma","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/3f5f08a8ba3e2bc991eb2fd8f8e3988c"},"headline":"O Morro dos Ventos Uivantes | Da Prateleira 05","datePublished":"2017-10-01T12:37:40+00:00","dateModified":"2023-06-03T19:10:59+00:00","mainEntityOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html"},"wordCount":279,"commentCount":6,"publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/09\/05-O-Morro-Dos-Ventos-Uivantes.jpg","keywords":["crentassos","da prateleira","emily bronte. emily bront\u00eb","eva holland","indica\u00e7\u00e3o","literatura","livro","o morro dos ventos uivantes","podcast","podcast de livro","podcasts","prateleira","tamyres palma","video-destaque"],"articleSection":["Da Prateleira","indica\u00e7\u00e3o","livro","livros","Podcasts"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html","url":"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html","name":"O Morro dos Ventos Uivantes | Da Prateleira 05 - Crentassos Produ\u00e7\u00f5es Subversivas","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#primaryimage"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/09\/05-O-Morro-Dos-Ventos-Uivantes.jpg","datePublished":"2017-10-01T12:37:40+00:00","dateModified":"2023-06-03T19:10:59+00:00","breadcrumb":{"@id":"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#primaryimage","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/09\/05-O-Morro-Dos-Ventos-Uivantes.jpg","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2017\/09\/05-O-Morro-Dos-Ventos-Uivantes.jpg","width":4418,"height":2492},{"@type":"BreadcrumbList","@id":"https:\/\/crentassos.com.br\/blog\/2017\/10\/da-prateleira-05-o-morro-dos-ventos-uivantes.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/crentassos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"O Morro dos Ventos Uivantes | Da Prateleira 05"}]},{"@type":"WebSite","@id":"https:\/\/crentassos.com.br\/blog\/#website","url":"https:\/\/crentassos.com.br\/blog\/","name":"Crentassos Produ\u00e7\u00f5es Subversivas","description":"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos","publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crentassos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/crentassos.com.br\/blog\/#organization","name":"Crentassos Produ\u00e7\u00f5es Subversivas","url":"https:\/\/crentassos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","width":300,"height":300,"caption":"Crentassos Produ\u00e7\u00f5es Subversivas"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/crentassos","https:\/\/x.com\/crentassos","https:\/\/www.instagram.com\/crentassos","https:\/\/www.youtube.com\/crentassos"]},{"@type":"Person","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/3f5f08a8ba3e2bc991eb2fd8f8e3988c","name":"Tamyres Palma","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9dce0caea2bafdb6394abc6c84348788083c31d52a278ed4b42bd0ee15c4ed52?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9dce0caea2bafdb6394abc6c84348788083c31d52a278ed4b42bd0ee15c4ed52?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9dce0caea2bafdb6394abc6c84348788083c31d52a278ed4b42bd0ee15c4ed52?s=96&d=retro&r=g","caption":"Tamyres Palma"},"description":"Tamyres Palma: formada em hist\u00f3ria, apaixonada por livros e casada com o @jonathazimmer . Maluca por Harry Potter, N\u00e1rnia e universos fant\u00e1sticos como a Terra M\u00e9dia. Apaixonada por literatura de forma geral, embora esteja longe do meu ideal de conhecimento liter\u00e1rio.","sameAs":["http:\/\/cafeecoberta.blogspot.com"],"url":"https:\/\/crentassos.com.br\/blog\/author\/tamyrespalma"}]}},"_links":{"self":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/13680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=13680"}],"version-history":[{"count":15,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/13680\/revisions"}],"predecessor-version":[{"id":21864,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/13680\/revisions\/21864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media\/13681"}],"wp:attachment":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=13680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=13680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=13680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}