{"id":11851,"date":"2015-09-24T15:47:09","date_gmt":"2015-09-24T18:47:09","guid":{"rendered":"http:\/\/crentassos.com.br\/blog\/?p=11851"},"modified":"2015-09-24T15:47:09","modified_gmt":"2015-09-24T18:47:09","slug":"postdoleitor-podemos-falar-sobre-vinganca","status":"publish","type":"post","link":"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html","title":{"rendered":"#PostDoLeitor &#8211; Podemos falar sobre vingan\u00e7a?"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2015\/09\/aaa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11852 alignleft\" src=\"http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2015\/09\/aaa-300x183.jpg\" alt=\"aaa\" width=\"300\" height=\"183\" srcset=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2015\/09\/aaa-300x183.jpg 300w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2015\/09\/aaa-620x377.jpg 620w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2015\/09\/aaa.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Recentemente um sentimento vingativo me aprisionou no \u00f3dio. Senti vertigens mentais. Meu cora\u00e7\u00e3o queimava de tanto furor. Meu corpo tremia ao ouvir aquela voz que me ati\u00e7ou a ira. Para mim, aquela voz soava como uma corda desafinada de um viol\u00e3o.Possu\u00eda-me e as veias dos meus olhos eram como rios de sangue em alta mar\u00e9. Sentia o pulsar na garganta, aquele que a gente sente quando tem raiva. Minha cabe\u00e7a s\u00f3 faltava estourar como se houvesse um homem bomba dentro dela.<\/p>\n<p style=\"text-align: justify\">Pode at\u00e9 parecer exagerado, mas era assim que me sentia at\u00e9 poucos dias atr\u00e1s.<\/p>\n<p style=\"text-align: justify\">Dias atr\u00e1s fui questionada por defender algumas minorias, no sentido pol\u00edtico, no meu local de trabalho, e n\u00e3o s\u00f3 questionada por isso, mas por defender e conhecer a b\u00edblia. Deixei bem claro que n\u00e3o falaria mal de ningu\u00e9m sem conhecer sua hist\u00f3ria de vida. Fui desmoralizada quando a minha profiss\u00e3o e quanto a minha f\u00e9 na presen\u00e7a de superiores.<\/p>\n<p style=\"text-align: justify\">Quanto mais eu pensava no que deveria ter dito \u00e0quela pessoa que me desmoralizou publicamente, mais eu me via afogada em \u00f3dio e mais me conhecia. Olhava para Deus e dizia o que Ele deveria fazer para me justificar, oras, eu estava defendendo a Sua causa.<\/p>\n<p style=\"text-align: justify\">N\u00e3o tinha mais a quem recorrer se n\u00e3o ao bom e velho Deus. N\u00e3o que ele fosse a \u00faltima op\u00e7\u00e3o, na verdade era a \u00fanica. Ent\u00e3o me senti como naquela cena de Matrix quando Neo encontra o arquiteto. Senti-me numa sala branca sem interfer\u00eancias externas. Sentei-me numa esp\u00e9cie de div\u00e3 e comecei n\u00e3o a contar-lhe o fato, mas maquinar para ele toda a situa\u00e7\u00e3o que eu desejava que tivesse ocorrido. Disse a Ele que eu escreveria uma carta. SiM! Uma carta rebatendo todos os argumentos equivocados da pessoa. Escreveria todos os textos b\u00edblicos e explicaria li\u00e7\u00f5es de escola dominical. Mostraria a ela que esses anos todos participando de cultos e eventos n\u00e3o eram suficientes para que conhecesse Deus e seus atributos.<\/p>\n<p style=\"text-align: justify\">Sim, eu sei que n\u00e3o estava errada quanto ao que fui questionada, sabia que, de acordo com os ensinamentos de Cristo e seus passos que eu conhecia muito bem, eu tomara a atitude correta. Irritava-me com o fundamentalismo que me questionava a f\u00e9. Irritei-me com as ideias reproduzidas sem conhecimento b\u00edblico. Enfureci-me por estar certa e ser desmoralizada por isso.<\/p>\n<p style=\"text-align: justify\">N\u00e3o demorei em notar que aquele sentimento fazia parte do meu dia. \u201cDeus, voc\u00ea n\u00e3o vai fazer nada? Desmoraliza esse \u201ccrente\u201d que me questiona quando eu estou certa\u201d. Cada dia mais eu sentia a necessidade de estar no palco enquanto ela estivesse na plateia. Queria que a minha vingan\u00e7a tivesse um gostinho de mel&#8230;<\/p>\n<p style=\"text-align: justify\">Ent\u00e3o acordei. Acordei entendendo o motivo do sil\u00eancio de Deus. Ele estava me mostrando o paradoxo onde me enfiei: Odiar os que odeiam. Afoguei-me nessa desgra\u00e7a! Quanto mais dizia pra Deus o que Ele deveria ter me feito falar, mais compreendia a minha derrota.<\/p>\n<p style=\"text-align: justify\">Ent\u00e3o mais uma vez me lembrei de Cristo. Aquele que t\u00e3o injustamente pagou um pre\u00e7o muito alto para me justificar. Injusti\u00e7ado, ferido, cuspido e assassinado pelos meus pecados e o mais interessante de tudo, Ele quis. Fez por amor e implorou o perd\u00e3o do Pai aos pecadores que o crucificavam, \u201celes n\u00e3o sabem o que fazem\u201d. Que seguidora de araque sou eu se n\u00e3o entender isso? Que crist\u00e3 sou eu se n\u00e3o compreender o real motivo de estar aqui? \u201cCarregue a sua cruz e me siga\u201d. Que crist\u00e3 sou eu se n\u00e3o compreender que aqueles que diziam conhecer tanto a Deus mataram Seu Filho?<\/p>\n<p style=\"text-align: justify\">E sa\u00ed deste pesadelo; o rio de \u00f3dio. Preferi nadar na fonte de \u00e1guas vivas.<\/p>\n<p style=\"text-align: justify\">Post de <a href=\"https:\/\/twitter.com\/Nine_Paiva\" target=\"_blank\">@Nine_Paiva<\/a><\/p>\n<p style=\"text-align: justify\">\u00a0<strong>***Post do leitor \u00e9 o espa\u00e7o para os leitores do blog colocarem seus pensamentos e tamb\u00e9m a porta de entrada do blog para novos editores. Os textos contidos aqui N\u00c3O condizem necessariamente com a opini\u00e3o dos editores do blog e nem caracteriza a necessariedade de o autor deste texto passar a fazer parte do elenco de editores do blog dos Crentassos.***<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recentemente um sentimento vingativo me aprisionou no \u00f3dio. Senti vertigens mentais. Meu cora\u00e7\u00e3o queimava de tanto furor. Meu corpo tremia ao ouvir [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":11852,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[119],"tags":[2864,1681],"class_list":["post-11851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-post-do-leitor","tag-vinganca","tag-postdoleitor","post-with-thumbnail","post-with-thumbnail-large"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#PostDoLeitor - Podemos falar sobre vingan\u00e7a? - Crentassos Produ\u00e7\u00f5es Subversivas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#PostDoLeitor - Podemos falar sobre vingan\u00e7a? - Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"og:description\" content=\"Recentemente um sentimento vingativo me aprisionou no \u00f3dio. Senti vertigens mentais. Meu cora\u00e7\u00e3o queimava de tanto furor. Meu corpo tremia ao ouvir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html\" \/>\n<meta property=\"og:site_name\" content=\"Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/crentassos\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-24T18:47:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2015\/09\/aaa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"779\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tamyres Palma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@crentassos\" \/>\n<meta name=\"twitter:site\" content=\"@crentassos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tamyres Palma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2015\\\/09\\\/postdoleitor-podemos-falar-sobre-vinganca.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2015\\\/09\\\/postdoleitor-podemos-falar-sobre-vinganca.html\"},\"author\":{\"name\":\"Tamyres Palma\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/3f5f08a8ba3e2bc991eb2fd8f8e3988c\"},\"headline\":\"#PostDoLeitor &#8211; Podemos falar sobre vingan\u00e7a?\",\"datePublished\":\"2015-09-24T18:47:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2015\\\/09\\\/postdoleitor-podemos-falar-sobre-vinganca.html\"},\"wordCount\":718,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2015\\\/09\\\/postdoleitor-podemos-falar-sobre-vinganca.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/aaa.jpg\",\"keywords\":[\"#vingan\u00e7a\",\"postdoleitor\"],\"articleSection\":[\"Post do Leitor\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2015\\\/09\\\/postdoleitor-podemos-falar-sobre-vinganca.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2015\\\/09\\\/postdoleitor-podemos-falar-sobre-vinganca.html\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2015\\\/09\\\/postdoleitor-podemos-falar-sobre-vinganca.html\",\"name\":\"#PostDoLeitor - Podemos falar sobre vingan\u00e7a? - Crentassos Produ\u00e7\u00f5es Subversivas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2015\\\/09\\\/postdoleitor-podemos-falar-sobre-vinganca.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2015\\\/09\\\/postdoleitor-podemos-falar-sobre-vinganca.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/aaa.jpg\",\"datePublished\":\"2015-09-24T18:47:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2015\\\/09\\\/postdoleitor-podemos-falar-sobre-vinganca.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2015\\\/09\\\/postdoleitor-podemos-falar-sobre-vinganca.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2015\\\/09\\\/postdoleitor-podemos-falar-sobre-vinganca.html#primaryimage\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/aaa.jpg\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/aaa.jpg\",\"width\":1280,\"height\":779},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2015\\\/09\\\/postdoleitor-podemos-falar-sobre-vinganca.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#PostDoLeitor &#8211; Podemos falar sobre vingan\u00e7a?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"description\":\"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"width\":300,\"height\":300,\"caption\":\"Crentassos Produ\u00e7\u00f5es Subversivas\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/crentassos\",\"https:\\\/\\\/x.com\\\/crentassos\",\"https:\\\/\\\/www.instagram.com\\\/crentassos\",\"https:\\\/\\\/www.youtube.com\\\/crentassos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/3f5f08a8ba3e2bc991eb2fd8f8e3988c\",\"name\":\"Tamyres Palma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dce0caea2bafdb6394abc6c84348788083c31d52a278ed4b42bd0ee15c4ed52?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dce0caea2bafdb6394abc6c84348788083c31d52a278ed4b42bd0ee15c4ed52?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dce0caea2bafdb6394abc6c84348788083c31d52a278ed4b42bd0ee15c4ed52?s=96&d=retro&r=g\",\"caption\":\"Tamyres Palma\"},\"description\":\"Tamyres Palma: formada em hist\u00f3ria, apaixonada por livros e casada com o @jonathazimmer . Maluca por Harry Potter, N\u00e1rnia e universos fant\u00e1sticos como a Terra M\u00e9dia. Apaixonada por literatura de forma geral, embora esteja longe do meu ideal de conhecimento liter\u00e1rio.\",\"sameAs\":[\"http:\\\/\\\/cafeecoberta.blogspot.com\"],\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/author\\\/tamyrespalma\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#PostDoLeitor - Podemos falar sobre vingan\u00e7a? - Crentassos Produ\u00e7\u00f5es Subversivas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html","og_locale":"pt_BR","og_type":"article","og_title":"#PostDoLeitor - Podemos falar sobre vingan\u00e7a? - Crentassos Produ\u00e7\u00f5es Subversivas","og_description":"Recentemente um sentimento vingativo me aprisionou no \u00f3dio. Senti vertigens mentais. Meu cora\u00e7\u00e3o queimava de tanto furor. Meu corpo tremia ao ouvir [&hellip;]","og_url":"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html","og_site_name":"Crentassos Produ\u00e7\u00f5es Subversivas","article_publisher":"http:\/\/www.facebook.com\/crentassos","article_published_time":"2015-09-24T18:47:09+00:00","og_image":[{"width":1280,"height":779,"url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2015\/09\/aaa.jpg","type":"image\/jpeg"}],"author":"Tamyres Palma","twitter_card":"summary_large_image","twitter_creator":"@crentassos","twitter_site":"@crentassos","twitter_misc":{"Escrito por":"Tamyres Palma","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html#article","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html"},"author":{"name":"Tamyres Palma","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/3f5f08a8ba3e2bc991eb2fd8f8e3988c"},"headline":"#PostDoLeitor &#8211; Podemos falar sobre vingan\u00e7a?","datePublished":"2015-09-24T18:47:09+00:00","mainEntityOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html"},"wordCount":718,"commentCount":0,"publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2015\/09\/aaa.jpg","keywords":["#vingan\u00e7a","postdoleitor"],"articleSection":["Post do Leitor"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html","url":"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html","name":"#PostDoLeitor - Podemos falar sobre vingan\u00e7a? - Crentassos Produ\u00e7\u00f5es Subversivas","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html#primaryimage"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2015\/09\/aaa.jpg","datePublished":"2015-09-24T18:47:09+00:00","breadcrumb":{"@id":"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html#primaryimage","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2015\/09\/aaa.jpg","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2015\/09\/aaa.jpg","width":1280,"height":779},{"@type":"BreadcrumbList","@id":"https:\/\/crentassos.com.br\/blog\/2015\/09\/postdoleitor-podemos-falar-sobre-vinganca.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/crentassos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"#PostDoLeitor &#8211; Podemos falar sobre vingan\u00e7a?"}]},{"@type":"WebSite","@id":"https:\/\/crentassos.com.br\/blog\/#website","url":"https:\/\/crentassos.com.br\/blog\/","name":"Crentassos Produ\u00e7\u00f5es Subversivas","description":"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos","publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crentassos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/crentassos.com.br\/blog\/#organization","name":"Crentassos Produ\u00e7\u00f5es Subversivas","url":"https:\/\/crentassos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","width":300,"height":300,"caption":"Crentassos Produ\u00e7\u00f5es Subversivas"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/crentassos","https:\/\/x.com\/crentassos","https:\/\/www.instagram.com\/crentassos","https:\/\/www.youtube.com\/crentassos"]},{"@type":"Person","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/3f5f08a8ba3e2bc991eb2fd8f8e3988c","name":"Tamyres Palma","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9dce0caea2bafdb6394abc6c84348788083c31d52a278ed4b42bd0ee15c4ed52?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9dce0caea2bafdb6394abc6c84348788083c31d52a278ed4b42bd0ee15c4ed52?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9dce0caea2bafdb6394abc6c84348788083c31d52a278ed4b42bd0ee15c4ed52?s=96&d=retro&r=g","caption":"Tamyres Palma"},"description":"Tamyres Palma: formada em hist\u00f3ria, apaixonada por livros e casada com o @jonathazimmer . Maluca por Harry Potter, N\u00e1rnia e universos fant\u00e1sticos como a Terra M\u00e9dia. Apaixonada por literatura de forma geral, embora esteja longe do meu ideal de conhecimento liter\u00e1rio.","sameAs":["http:\/\/cafeecoberta.blogspot.com"],"url":"https:\/\/crentassos.com.br\/blog\/author\/tamyrespalma"}]}},"_links":{"self":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/11851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=11851"}],"version-history":[{"count":3,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/11851\/revisions"}],"predecessor-version":[{"id":11856,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/11851\/revisions\/11856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media\/11852"}],"wp:attachment":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=11851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=11851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=11851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}