{"id":11000,"date":"2014-09-03T10:14:17","date_gmt":"2014-09-03T13:14:17","guid":{"rendered":"http:\/\/crentassos.com.br\/blog\/?p=11000"},"modified":"2014-09-03T10:14:17","modified_gmt":"2014-09-03T13:14:17","slug":"terminei-evangelho-maltrapilho","status":"publish","type":"post","link":"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html","title":{"rendered":"#TERMINEI &#8211; Evangelho Maltrapilho"},"content":{"rendered":"<p>A algum tempo atr\u00e1s, ganhei de presente de um grande amigo, uma c\u00f3pia do aclamado O EVANGELHO MALTRAPILHO, escrito pelo estadosunidense, Brennan Manning.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11001 alignleft\" alt=\"O_evangelho_maltrapilho_detp\" src=\"http:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/O_evangelho_maltrapilho_detp.jpg\" width=\"350\" height=\"350\" srcset=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/O_evangelho_maltrapilho_detp.jpg 350w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/O_evangelho_maltrapilho_detp-150x150.jpg 150w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/O_evangelho_maltrapilho_detp-300x300.jpg 300w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/O_evangelho_maltrapilho_detp-62x62.jpg 62w, https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/O_evangelho_maltrapilho_detp-256x256.jpg 256w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/>Na verdade o presente se deu no contexto de que ao conversar com o querid\u00edssimo Osmar Ludovico, perguntei se ele teria uma biografia b\u00e1sica para quem quisesse buscar uma espiritualidade mais simples e encarnada e, numa lista de dez livros, a obra em quest\u00e3o havia sido citada.<\/p>\n<p>Para inicio de conversa, h\u00e1 um trecho, logo no inicio h\u00e1 uma introdu\u00e7\u00e3o chamada \u201cUma palavra antes de come\u00e7ar\u201d de apenas duas paginas e apenas nessa trecho, j\u00e1 me apaixonei pelo texto. Esse textinho diz para quem foi escrito e para quem n\u00e3o foi escrito, e \u00e9 claro, me identifiquei exatamente com o alvo do texto.<\/p>\n<p>Ao longo das paginas do livro, o evangelho apote\u00f3tico dos homens e mulheres generais de Deus, vai dando espa\u00e7o para um evangelho que mais se parece com um abrigo para moradores de rua que precisam de comida, banho e uma cama para dormir, longe dos perigos da sarjeta das grandes cidades, o evangelho de Cristo \u00e9 encarado como uma ESCUDO e n\u00e3o como um ESPADA.<\/p>\n<p>Claro, \u00e9 uma tolice completa, achar que o autor revolucionou alguma coisa, pois as palavras dele, n\u00e3o s\u00e3o nem um pouco originais, se comparadas ao texto b\u00edblico, a \u00fanica coisa que Brennan faz, \u00e9 expor aos nossos olhos cascudos com o tempo e a religiosidade, tudo aquilo que sempre esteve escrito l\u00e1 na b\u00edblia.<\/p>\n<p>Vemos neste livro v\u00e1rios testemunhos, alegorias, palavras duras e sobre tudo, tentativa de se render diante de Deus, largar as armas da prepot\u00eancia evang\u00e9lica t\u00e3o difundida e aplaudida por tantos webteologos nos nossos dias, o livro poderia ser resumido na frase:<\/p>\n<p>\u201cOk, Deus&#8230; Eu desisto, n\u00e3o tenho capacidade de ser \u00a0um crist\u00e3o \u201cperfeito\u201d&#8230; Eu me entrego\u201d<\/p>\n<p>Posso aconselhar, a todos que n\u00e3o tem medo de repensar seus conceito e de rever suas verdades, mas n\u00e3o acho que seja bom para quem tem certeza absoluta que consegui colocar um arreio em Deus e agora est\u00e1 sob o total controle da sua experi\u00eancia crist\u00e3.<\/p>\n<p>O Livro \u00e9 de f\u00e1cil leitura e acess\u00edvel a qualquer pessoa.<\/p>\n<p>Vale cada pagina!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A algum tempo atr\u00e1s, ganhei de presente de um grande amigo, uma c\u00f3pia do aclamado O EVANGELHO MALTRAPILHO, escrito pelo estadosunidense, Brennan [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":11001,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[112],"tags":[1483,2615,1870,49,2616,2617],"class_list":["post-11000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","tag-brennan-manning","tag-evangelho-maltrapilho","tag-livro","tag-terminei","tag-vida-crista-simples","tag-vida-simples","post-with-thumbnail","post-with-thumbnail-large"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#TERMINEI - Evangelho Maltrapilho  - Crentassos Produ\u00e7\u00f5es Subversivas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#TERMINEI - Evangelho Maltrapilho  - Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"og:description\" content=\"A algum tempo atr\u00e1s, ganhei de presente de um grande amigo, uma c\u00f3pia do aclamado O EVANGELHO MALTRAPILHO, escrito pelo estadosunidense, Brennan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html\" \/>\n<meta property=\"og:site_name\" content=\"Crentassos Produ\u00e7\u00f5es Subversivas\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/crentassos\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-03T13:14:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/O_evangelho_maltrapilho_detp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristiano Machado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@crentassos\" \/>\n<meta name=\"twitter:site\" content=\"@crentassos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristiano Machado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2014\\\/09\\\/terminei-evangelho-maltrapilho.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2014\\\/09\\\/terminei-evangelho-maltrapilho.html\"},\"author\":{\"name\":\"Cristiano Machado\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/7ec3329a98c44e20ccd6cc2c9e18acbd\"},\"headline\":\"#TERMINEI &#8211; Evangelho Maltrapilho\",\"datePublished\":\"2014-09-03T13:14:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2014\\\/09\\\/terminei-evangelho-maltrapilho.html\"},\"wordCount\":386,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2014\\\/09\\\/terminei-evangelho-maltrapilho.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/O_evangelho_maltrapilho_detp.jpg\",\"keywords\":[\"Brennan Manning\",\"evangelho maltrapilho\",\"livro\",\"terminei\",\"vida crist\u00e3 simples\",\"vida simples\"],\"articleSection\":[\"Artigos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2014\\\/09\\\/terminei-evangelho-maltrapilho.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2014\\\/09\\\/terminei-evangelho-maltrapilho.html\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2014\\\/09\\\/terminei-evangelho-maltrapilho.html\",\"name\":\"#TERMINEI - Evangelho Maltrapilho - Crentassos Produ\u00e7\u00f5es Subversivas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2014\\\/09\\\/terminei-evangelho-maltrapilho.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2014\\\/09\\\/terminei-evangelho-maltrapilho.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/O_evangelho_maltrapilho_detp.jpg\",\"datePublished\":\"2014-09-03T13:14:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2014\\\/09\\\/terminei-evangelho-maltrapilho.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2014\\\/09\\\/terminei-evangelho-maltrapilho.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2014\\\/09\\\/terminei-evangelho-maltrapilho.html#primaryimage\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/O_evangelho_maltrapilho_detp.jpg\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/O_evangelho_maltrapilho_detp.jpg\",\"width\":350,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/2014\\\/09\\\/terminei-evangelho-maltrapilho.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#TERMINEI &#8211; Evangelho Maltrapilho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"description\":\"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#organization\",\"name\":\"Crentassos Produ\u00e7\u00f5es Subversivas\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"contentUrl\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-crentassos1-300x300png.png\",\"width\":300,\"height\":300,\"caption\":\"Crentassos Produ\u00e7\u00f5es Subversivas\"},\"image\":{\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/crentassos\",\"https:\\\/\\\/x.com\\\/crentassos\",\"https:\\\/\\\/www.instagram.com\\\/crentassos\",\"https:\\\/\\\/www.youtube.com\\\/crentassos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/7ec3329a98c44e20ccd6cc2c9e18acbd\",\"name\":\"Cristiano Machado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g\",\"caption\":\"Cristiano Machado\"},\"description\":\"Cristiano Machado \u00e9 o culpado pelo inicio do COLETIVO CRENTASSOS PRODU\u00c7\u00d5ES SUBVERSIVAS e atua como auxiliar de cirurgi\u00e3o barbeiro, tocando o bumbo, jogando malabares, preparando o elixir, costurando amputa\u00e7\u00f5es e demais atividades relacionadas \u00e0 sua ocupa\u00e7\u00e3o. Pensa n\u00e3o vida em forma de pergunta e nunca de resposta, e tem um profundo sentimento de gratid\u00e3o e amor por sua esposa e filha. Religi\u00e3o: Crist\u00e3o Protestante Reformando-se Estado Civil: Inteiramente apaixonado\",\"sameAs\":[\"http:\\\/\\\/crentassos.com.br\\\/blog\"],\"url\":\"https:\\\/\\\/crentassos.com.br\\\/blog\\\/author\\\/o_cristiano\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#TERMINEI - Evangelho Maltrapilho  - Crentassos Produ\u00e7\u00f5es Subversivas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html","og_locale":"pt_BR","og_type":"article","og_title":"#TERMINEI - Evangelho Maltrapilho  - Crentassos Produ\u00e7\u00f5es Subversivas","og_description":"A algum tempo atr\u00e1s, ganhei de presente de um grande amigo, uma c\u00f3pia do aclamado O EVANGELHO MALTRAPILHO, escrito pelo estadosunidense, Brennan [&hellip;]","og_url":"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html","og_site_name":"Crentassos Produ\u00e7\u00f5es Subversivas","article_publisher":"http:\/\/www.facebook.com\/crentassos","article_published_time":"2014-09-03T13:14:17+00:00","og_image":[{"width":350,"height":350,"url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/O_evangelho_maltrapilho_detp.jpg","type":"image\/jpeg"}],"author":"Cristiano Machado","twitter_card":"summary_large_image","twitter_creator":"@crentassos","twitter_site":"@crentassos","twitter_misc":{"Escrito por":"Cristiano Machado","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html#article","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html"},"author":{"name":"Cristiano Machado","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/7ec3329a98c44e20ccd6cc2c9e18acbd"},"headline":"#TERMINEI &#8211; Evangelho Maltrapilho","datePublished":"2014-09-03T13:14:17+00:00","mainEntityOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html"},"wordCount":386,"commentCount":3,"publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/O_evangelho_maltrapilho_detp.jpg","keywords":["Brennan Manning","evangelho maltrapilho","livro","terminei","vida crist\u00e3 simples","vida simples"],"articleSection":["Artigos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html","url":"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html","name":"#TERMINEI - Evangelho Maltrapilho - Crentassos Produ\u00e7\u00f5es Subversivas","isPartOf":{"@id":"https:\/\/crentassos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html#primaryimage"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html#primaryimage"},"thumbnailUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/O_evangelho_maltrapilho_detp.jpg","datePublished":"2014-09-03T13:14:17+00:00","breadcrumb":{"@id":"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html#primaryimage","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/O_evangelho_maltrapilho_detp.jpg","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/O_evangelho_maltrapilho_detp.jpg","width":350,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/crentassos.com.br\/blog\/2014\/09\/terminei-evangelho-maltrapilho.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/crentassos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"#TERMINEI &#8211; Evangelho Maltrapilho"}]},{"@type":"WebSite","@id":"https:\/\/crentassos.com.br\/blog\/#website","url":"https:\/\/crentassos.com.br\/blog\/","name":"Crentassos Produ\u00e7\u00f5es Subversivas","description":"Podcast Crist\u00e3o, Podcrent, Da Prateleira, Artigos crist\u00e3os, Teologia, Estudos, Textos B\u00edblicos","publisher":{"@id":"https:\/\/crentassos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crentassos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/crentassos.com.br\/blog\/#organization","name":"Crentassos Produ\u00e7\u00f5es Subversivas","url":"https:\/\/crentassos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","contentUrl":"https:\/\/crentassos.com.br\/blog\/wp-content\/uploads\/2020\/05\/cropped-crentassos1-300x300png.png","width":300,"height":300,"caption":"Crentassos Produ\u00e7\u00f5es Subversivas"},"image":{"@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/crentassos","https:\/\/x.com\/crentassos","https:\/\/www.instagram.com\/crentassos","https:\/\/www.youtube.com\/crentassos"]},{"@type":"Person","@id":"https:\/\/crentassos.com.br\/blog\/#\/schema\/person\/7ec3329a98c44e20ccd6cc2c9e18acbd","name":"Cristiano Machado","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e7427d384f99d15935b3008477c324124816869ceb70e362e586dcccdb265bf?s=96&d=retro&r=g","caption":"Cristiano Machado"},"description":"Cristiano Machado \u00e9 o culpado pelo inicio do COLETIVO CRENTASSOS PRODU\u00c7\u00d5ES SUBVERSIVAS e atua como auxiliar de cirurgi\u00e3o barbeiro, tocando o bumbo, jogando malabares, preparando o elixir, costurando amputa\u00e7\u00f5es e demais atividades relacionadas \u00e0 sua ocupa\u00e7\u00e3o. Pensa n\u00e3o vida em forma de pergunta e nunca de resposta, e tem um profundo sentimento de gratid\u00e3o e amor por sua esposa e filha. Religi\u00e3o: Crist\u00e3o Protestante Reformando-se Estado Civil: Inteiramente apaixonado","sameAs":["http:\/\/crentassos.com.br\/blog"],"url":"https:\/\/crentassos.com.br\/blog\/author\/o_cristiano"}]}},"_links":{"self":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/11000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=11000"}],"version-history":[{"count":1,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/11000\/revisions"}],"predecessor-version":[{"id":11002,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/posts\/11000\/revisions\/11002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media\/11001"}],"wp:attachment":[{"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=11000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=11000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crentassos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=11000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}